{"id":2603,"date":"2022-03-01T16:56:47","date_gmt":"2022-03-01T15:56:47","guid":{"rendered":"https:\/\/www.setterirlandese.net\/irish-setter-female\/"},"modified":"2025-12-05T17:41:41","modified_gmt":"2025-12-05T16:41:41","slug":"irish-setter-female","status":"publish","type":"page","link":"https:\/\/www.setterirlandese.net\/en\/irish-setter-female\/","title":{"rendered":"Irish Setter female"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"2603\" class=\"elementor elementor-2603 elementor-864\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-d1514f4 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d1514f4\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-31a45c8\" data-id=\"31a45c8\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ae4bf3f elementor-widget elementor-widget-heading\" data-id=\"ae4bf3f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Irish Setter female<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d202618 elementor-widget elementor-widget-text-editor\" data-id=\"d202618\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Female Irish Setters &#8211; Welcome to the page, below you can find out which females are part of our kennel. Some of them are champions, others young promises and still others excellent bitches but all rigorously healthy and adhering to the standard of the Irish setter both in terms of appearance and character. Through this page you can also consult the pedigree of each of our subjects.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3ce2bb6 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3ce2bb6\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-1776e2d\" data-id=\"1776e2d\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-fc0997e elementor-widget elementor-widget-heading\" data-id=\"fc0997e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">SDR Aisling<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0ab0adc elementor--h-position-center elementor--v-position-middle elementor-arrows-position-inside elementor-pagination-position-inside elementor-widget elementor-widget-slides\" data-id=\"0ab0adc\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;autoplay_speed&quot;:3000,&quot;navigation&quot;:&quot;both&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;infinite&quot;:&quot;yes&quot;,&quot;transition&quot;:&quot;slide&quot;,&quot;transition_speed&quot;:500}\" data-widget_type=\"slides.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper\">\n\t\t\t\t\t<div class=\"elementor-slides-wrapper elementor-main-swiper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Slides\" dir=\"ltr\" data-animation=\"fadeInUp\">\n\t\t\t\t<div class=\"swiper-wrapper elementor-slides\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-repeater-item-7998ec6 swiper-slide\" role=\"group\" aria-roledescription=\"slide\"><div class=\"swiper-slide-bg\" role=\"img\" aria-label=\"srdaisling002\"><\/div><div class=\"swiper-slide-inner\" ><div class=\"swiper-slide-contents\"><\/div><\/div><\/div><div class=\"elementor-repeater-item-2fc51aa swiper-slide\" role=\"group\" aria-roledescription=\"slide\"><div class=\"swiper-slide-bg\" role=\"img\" aria-label=\"srdaisling003\"><\/div><div class=\"swiper-slide-inner\" ><div class=\"swiper-slide-contents\"><\/div><\/div><\/div><div class=\"elementor-repeater-item-414bd33 swiper-slide\" role=\"group\" aria-roledescription=\"slide\"><div class=\"swiper-slide-bg\" role=\"img\" aria-label=\"srdaisling004\"><\/div><div class=\"swiper-slide-inner\" ><div class=\"swiper-slide-contents\"><\/div><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\" aria-label=\"Previous slide\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-chevron-left\" viewBox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M646 125C629 125 613 133 604 142L308 442C296 454 292 471 292 487 292 504 296 521 308 533L604 854C617 867 629 875 646 875 663 875 679 871 692 858 704 846 713 829 713 812 713 796 708 779 692 767L438 487 692 225C700 217 708 204 708 187 708 171 704 154 692 142 675 129 663 125 646 125Z\"><\/path><\/svg>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\" aria-label=\"Next slide\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-chevron-right\" viewBox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M696 533C708 521 713 504 713 487 713 471 708 454 696 446L400 146C388 133 375 125 354 125 338 125 325 129 313 142 300 154 292 171 292 187 292 204 296 221 308 233L563 492 304 771C292 783 288 800 288 817 288 833 296 850 308 863 321 871 338 875 354 875 371 875 388 867 400 854L696 533Z\"><\/path><\/svg>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-pagination\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-bef38b7 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"bef38b7\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-57bd989\" data-id=\"57bd989\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4045999 elementor-list-item-link-inline elementor-icon-list--layout-traditional elementor-widget elementor-widget-icon-list\" data-id=\"4045999\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" id=\"Capa_1\" x=\"0px\" y=\"0px\" viewBox=\"0 0 512 512\" style=\"enable-background:new 0 0 512 512;\" xml:space=\"preserve\"><g>\t<g>\t\t<g>\t\t\t<g>\t\t\t\t<g>\t\t\t\t\t<ellipse cx=\"294.2\" cy=\"103.1\" rx=\"10\" ry=\"12.9\"><\/ellipse>\t\t\t\t<\/g>\t\t\t<\/g>\t\t<\/g>\t<\/g>\t<g>\t\t<path d=\"M16.3,138.1c-2.1,3.6-0.8,8.2,2.8,10.2c1.2,0.7,2.4,1,3.7,1c2.6,0,5.1-1.4,6.5-3.8l43.1-75.8   c14.9-26.1,40.1-45.2,69.3-52.5c13.5-3.3,27.7-3.1,41.1,0.7l34.8,9.8c4,1.1,8.1-1.2,9.3-5.2c1.1-4-1.2-8.1-5.2-9.3l-34.8-9.8   c-15.9-4.5-32.7-4.8-48.8-0.8C105,11,76.3,32.7,59.4,62.4L16.3,138.1L16.3,138.1z\"><\/path>\t\t<path d=\"M493.4,175.4c4-7.6,4.4-16.5,1.1-24.5c-3.3-7.9-9.9-13.9-18.1-16.4L336.5,90.2l-0.9-2.4c-11-29.5-35.7-52.3-66-60.9   l-18.2-5.2c-4-1.1-8.1,1.2-9.3,5.2s1.2,8.1,5.2,9.3l18.2,5.2c25.8,7.3,46.7,26.6,56,51.7l2.2,5.8c0.8,2.2,2.5,3.8,4.7,4.5   l91.9,29.5c-6.2,35.2,4.5,57,14.9,69.2c7,8.2,14.7,13.2,20.1,16l-6.7,19.6c-8.3,24.1-31,40.3-56.4,40.3h-57.5   c-4.1,0-7.5,3.4-7.5,7.5s3.4,7.5,7.5,7.5h57.5c31.9,0,60.3-20.3,70.6-50.4l8.5-24.7L493.4,175.4z M461.3,204.3   c-11-5.9-33.3-23.6-26.5-66.9l37.2,11.4c3.9,1.2,7.1,4.1,8.7,7.9c1.6,3.8,1.4,8.1-0.5,11.7L461.3,204.3L461.3,204.3z\"><\/path>\t\t<path d=\"M59.7,362.9c-4.1,0.2-7.3,3.7-7.1,7.9c2.2,44.1,9.6,54.7,23.7,70.9c5.5,6.4,11.7,13.6,19.1,25.6   c16.2,26.4,46.9,44.7,72.7,44.7c3.6,0,7.1-0.4,10.5-1.1c10.9-2.4,29.8-11.1,33.3-42.3c2.9-25.6,11.6-37.8,20.7-50.7   c11.2-15.8,22.8-32.1,23.5-70.4c0.3-16-3.3-31.6-8.9-47c10.7-5,22.7-7.6,34.7-7.6h23.8c4.1,0,7.5-3.4,7.5-7.5s-3.4-7.5-7.5-7.5   H282c-14,0-27.8,3-40.3,8.6c-4.6-10.7-9.9-21.2-15.1-31.7c-16.8-33.8-32.8-65.7-20-92c12.6-26.1,15.7-51.3,15.3-71l12-26   c1.7-3.8,0.1-8.2-3.7-10c-3.8-1.7-8.2-0.1-10,3.7l-1.6,3.5c-1.2-5.9-2.4-9.5-2.6-10c-1.3-3.9-5.6-6-9.5-4.7   c-3.9,1.3-6,5.6-4.7,9.5c0.2,0.5,15.5,48.3-8.8,98.4c-16,33,1.6,68.1,20.1,105.3c14,28.1,28.5,57.2,28,85.6   c-0.7,33.7-10.4,47.5-20.8,62c-9.8,13.9-20,28.2-23.4,57.7c-1.9,16.7-9.2,26.6-21.7,29.4c-21.3,4.7-52.1-12.1-67.2-36.8   c-8-13-14.9-21.1-20.5-27.5c-12-13.9-18-20.9-20.1-61.9C67.4,365.9,63.8,362.7,59.7,362.9L59.7,362.9z\"><\/path>\t\t<path d=\"M70.5,199.3c4.8,37-0.7,55.3-7,76.6c-4.8,16.3-10.3,34.8-11.4,63.4c-0.2,4.1,3.1,7.6,7.2,7.8c0.1,0,0.2,0,0.3,0   c4,0,7.3-3.2,7.5-7.2c1-26.7,5.9-43.5,10.7-59.7c6.5-22,12.7-42.7,7.5-82.8C78.7,146.1,89.3,96,112.2,69.9   c11.5-13,25.6-19.7,41.9-19.7c4.1,0,7.5-3.4,7.5-7.5s-3.4-7.5-7.5-7.5c-20.5,0-38.9,8.6-53.1,24.8   C75.3,89.2,63.3,143.9,70.5,199.3L70.5,199.3z\"><\/path>\t\t<path d=\"M124,116.1c-1.2,1.9-28.8,46.7-8.3,115.4c9.4,31.7,3.1,55.4-3.6,80.4c-6.6,24.4-13.3,49.7-3.5,81.2c1,3.2,4,5.3,7.2,5.3   c0.7,0,1.5-0.1,2.2-0.3c4-1.2,6.2-5.4,4.9-9.4c-8.5-27.3-2.6-49.4,3.7-72.8c7-26,14.2-52.8,3.5-88.6   c-18.4-61.9,6.4-102.7,6.6-103.1c2.2-3.5,1.1-8.1-2.4-10.3C130.8,111.6,126.2,112.6,124,116.1L124,116.1z\"><\/path>\t\t<path d=\"M160.9,470.9c3.3-0.7,5.7-3.5,5.8-6.9c0.5-9.6,4.9-31.6,29.5-64.6c16.3-22,22.5-48.2,17.9-75.7   c-3.4-20.6-11.7-34.7-12.1-35.3c-2.1-3.6-6.7-4.7-10.3-2.6c-3.6,2.1-4.7,6.7-2.6,10.3c0.2,0.3,7.4,12.8,10.3,30.7   c3.8,23.6-1.3,45-15.3,63.7c-26.4,35.5-31.8,60.1-32.5,72.7C151.5,468.2,156,472,160.9,470.9L160.9,470.9z\"><\/path>\t\t<path d=\"M159.6,300.4c-4.1-0.2-7.7,2.9-7.9,7c0,0.3-1.7,27.7-5,46.1c-0.7,4.1,2,8,6.1,8.7c0.4,0.1,0.9,0.1,1.3,0.1   c3.6,0,6.7-2.6,7.4-6.2c3.4-19.2,5.1-46.6,5.2-47.8C166.9,304.2,163.8,300.7,159.6,300.4L159.6,300.4z\"><\/path>\t\t<path d=\"M170.5,81.7c0.1,0.6,5.6,45.5-25.3,76.4c-2.9,2.9-2.9,7.7,0,10.6c1.5,1.5,3.4,2.2,5.3,2.2c1.9,0,3.8-0.7,5.3-2.2   c36.4-36.4,29.9-86.9,29.6-89.1c-0.6-4.1-4.3-7-8.5-6.4C172.8,73.8,170,77.6,170.5,81.7z\"><\/path>\t<\/g><\/g><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Born : 06\/12\/2023<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ec46878 elementor-list-item-link-inline elementor-icon-list--layout-traditional elementor-widget elementor-widget-icon-list\" data-id=\"ec46878\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" id=\"Capa_1\" x=\"0px\" y=\"0px\" viewBox=\"0 0 512 512\" style=\"enable-background:new 0 0 512 512;\" xml:space=\"preserve\"><g>\t<g>\t\t<path d=\"M376.264,290.173c66.314-66.293,66.314-174.16,0-240.453c-66.314-66.294-174.214-66.294-240.529,0   c-66.314,66.293-66.314,174.16,0,240.453c28.07,28.061,63.591,44.24,100.254,48.546v56.923h-40.018   c-11.051,0-20.009,8.956-20.009,20.003s8.958,20.003,20.009,20.003h40.018v56.348c0.001,11.047,8.959,20.003,20.011,20.003   c11.051,0,20.009-8.956,20.009-20.003v-56.348h40.019c11.051,0,20.009-8.956,20.009-20.003s-8.958-20.003-20.009-20.003h-40.019   V338.72C312.673,334.413,348.194,318.234,376.264,290.173z M164.033,261.884c-50.711-50.695-50.711-133.181,0-183.876   c50.71-50.693,133.221-50.696,183.934,0c50.711,50.695,50.711,133.181,0,183.876C297.256,312.578,214.744,312.578,164.033,261.884   z\"><\/path>\t<\/g><\/g><g><\/g><g><\/g><g><\/g><g><\/g><g><\/g><g><\/g><g><\/g><g><\/g><g><\/g><g><\/g><g><\/g><g><\/g><g><\/g><g><\/g><g><\/g><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">SRD Capital Gain<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ab07ef7 elementor-list-item-link-inline elementor-icon-list--layout-traditional elementor-widget elementor-widget-icon-list\" data-id=\"ab07ef7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" height=\"512\" viewBox=\"0 0 64 64\" width=\"512\"><g id=\"_14._Men_sign\" data-name=\"14. Men sign\"><path d=\"m61 5v20.76a2 2 0 0 1 -2 2h-2.62a2 2 0 0 1 -2-2v-11.14c-.02.02-14.42 14.42-14.45 14.44 9.647 13.666-.652 32.711-17.59 31.92a20.323 20.323 0 0 1 -19.32-21.27c.74-15.817 18.86-24.861 31.93-15.66l14.43-14.43h-11.14a2 2 0 0 1 -2-2v-2.62a2 2 0 0 1 2-2h20.76a2 2 0 0 1 2 2zm-24.81 35.69a12.875 12.875 0 1 0 -12.88 12.87 12.884 12.884 0 0 0 12.88-12.87z\" fill=\"#a5ccf2\"><\/path><\/g><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Brighton<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-5344d97\" data-id=\"5344d97\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4a5316a elementor-align-center elementor-mobile-align-left elementor-widget elementor-widget-button\" data-id=\"4a5316a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.setterirlandese.net\/wp-content\/uploads\/2025\/06\/srd-aisling-pedigree.pdf\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">PEDIGREE<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-64fdcdd elementor-align-center elementor-mobile-align-left elementor-widget elementor-widget-button\" data-id=\"64fdcdd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.setterirlandese.net\/wp-content\/uploads\/2025\/06\/srd-aisling-pedigree.pdf\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Hd B Ed O<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-6e48c97\" data-id=\"6e48c97\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f1f9c16 elementor-widget elementor-widget-heading\" data-id=\"f1f9c16\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Perla di Casa Bertolini<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-eefabee elementor--h-position-center elementor--v-position-middle elementor-arrows-position-inside elementor-pagination-position-inside elementor-widget elementor-widget-slides\" data-id=\"eefabee\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;autoplay_speed&quot;:3000,&quot;navigation&quot;:&quot;both&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;infinite&quot;:&quot;yes&quot;,&quot;transition&quot;:&quot;slide&quot;,&quot;transition_speed&quot;:500}\" data-widget_type=\"slides.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper\">\n\t\t\t\t\t<div class=\"elementor-slides-wrapper elementor-main-swiper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Slides\" dir=\"ltr\" data-animation=\"fadeInUp\">\n\t\t\t\t<div class=\"swiper-wrapper elementor-slides\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-repeater-item-fce16ce swiper-slide\" role=\"group\" aria-roledescription=\"slide\"><div class=\"swiper-slide-bg\" role=\"img\" aria-label=\"perla-di-casa-bertolini001\"><\/div><div class=\"swiper-slide-inner\" ><div class=\"swiper-slide-contents\"><\/div><\/div><\/div><div class=\"elementor-repeater-item-576d0d6 swiper-slide\" role=\"group\" aria-roledescription=\"slide\"><div class=\"swiper-slide-bg\" role=\"img\" aria-label=\"perla-di-casa-bertolini002\"><\/div><div class=\"swiper-slide-inner\" ><div class=\"swiper-slide-contents\"><\/div><\/div><\/div><div class=\"elementor-repeater-item-1da7737 swiper-slide\" role=\"group\" aria-roledescription=\"slide\"><div class=\"swiper-slide-bg\" role=\"img\" aria-label=\"perla-di-casa-bertolini003\"><\/div><div class=\"swiper-slide-inner\" ><div class=\"swiper-slide-contents\"><\/div><\/div><\/div><div class=\"elementor-repeater-item-e4d17ca swiper-slide\" role=\"group\" aria-roledescription=\"slide\"><div class=\"swiper-slide-bg\" role=\"img\" aria-label=\"perla-di-casa-bertolini004\"><\/div><div class=\"swiper-slide-inner\" ><div class=\"swiper-slide-contents\"><\/div><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\" aria-label=\"Previous slide\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-chevron-left\" viewBox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M646 125C629 125 613 133 604 142L308 442C296 454 292 471 292 487 292 504 296 521 308 533L604 854C617 867 629 875 646 875 663 875 679 871 692 858 704 846 713 829 713 812 713 796 708 779 692 767L438 487 692 225C700 217 708 204 708 187 708 171 704 154 692 142 675 129 663 125 646 125Z\"><\/path><\/svg>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\" aria-label=\"Next slide\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-chevron-right\" viewBox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M696 533C708 521 713 504 713 487 713 471 708 454 696 446L400 146C388 133 375 125 354 125 338 125 325 129 313 142 300 154 292 171 292 187 292 204 296 221 308 233L563 492 304 771C292 783 288 800 288 817 288 833 296 850 308 863 321 871 338 875 354 875 371 875 388 867 400 854L696 533Z\"><\/path><\/svg>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-pagination\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-3f03b24 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3f03b24\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-51edbd0\" data-id=\"51edbd0\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-51ea9c7 elementor-list-item-link-inline elementor-icon-list--layout-traditional elementor-widget elementor-widget-icon-list\" data-id=\"51ea9c7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" id=\"Capa_1\" x=\"0px\" y=\"0px\" viewBox=\"0 0 512 512\" style=\"enable-background:new 0 0 512 512;\" xml:space=\"preserve\"><g>\t<g>\t\t<g>\t\t\t<g>\t\t\t\t<g>\t\t\t\t\t<ellipse cx=\"294.2\" cy=\"103.1\" rx=\"10\" ry=\"12.9\"><\/ellipse>\t\t\t\t<\/g>\t\t\t<\/g>\t\t<\/g>\t<\/g>\t<g>\t\t<path d=\"M16.3,138.1c-2.1,3.6-0.8,8.2,2.8,10.2c1.2,0.7,2.4,1,3.7,1c2.6,0,5.1-1.4,6.5-3.8l43.1-75.8   c14.9-26.1,40.1-45.2,69.3-52.5c13.5-3.3,27.7-3.1,41.1,0.7l34.8,9.8c4,1.1,8.1-1.2,9.3-5.2c1.1-4-1.2-8.1-5.2-9.3l-34.8-9.8   c-15.9-4.5-32.7-4.8-48.8-0.8C105,11,76.3,32.7,59.4,62.4L16.3,138.1L16.3,138.1z\"><\/path>\t\t<path d=\"M493.4,175.4c4-7.6,4.4-16.5,1.1-24.5c-3.3-7.9-9.9-13.9-18.1-16.4L336.5,90.2l-0.9-2.4c-11-29.5-35.7-52.3-66-60.9   l-18.2-5.2c-4-1.1-8.1,1.2-9.3,5.2s1.2,8.1,5.2,9.3l18.2,5.2c25.8,7.3,46.7,26.6,56,51.7l2.2,5.8c0.8,2.2,2.5,3.8,4.7,4.5   l91.9,29.5c-6.2,35.2,4.5,57,14.9,69.2c7,8.2,14.7,13.2,20.1,16l-6.7,19.6c-8.3,24.1-31,40.3-56.4,40.3h-57.5   c-4.1,0-7.5,3.4-7.5,7.5s3.4,7.5,7.5,7.5h57.5c31.9,0,60.3-20.3,70.6-50.4l8.5-24.7L493.4,175.4z M461.3,204.3   c-11-5.9-33.3-23.6-26.5-66.9l37.2,11.4c3.9,1.2,7.1,4.1,8.7,7.9c1.6,3.8,1.4,8.1-0.5,11.7L461.3,204.3L461.3,204.3z\"><\/path>\t\t<path d=\"M59.7,362.9c-4.1,0.2-7.3,3.7-7.1,7.9c2.2,44.1,9.6,54.7,23.7,70.9c5.5,6.4,11.7,13.6,19.1,25.6   c16.2,26.4,46.9,44.7,72.7,44.7c3.6,0,7.1-0.4,10.5-1.1c10.9-2.4,29.8-11.1,33.3-42.3c2.9-25.6,11.6-37.8,20.7-50.7   c11.2-15.8,22.8-32.1,23.5-70.4c0.3-16-3.3-31.6-8.9-47c10.7-5,22.7-7.6,34.7-7.6h23.8c4.1,0,7.5-3.4,7.5-7.5s-3.4-7.5-7.5-7.5   H282c-14,0-27.8,3-40.3,8.6c-4.6-10.7-9.9-21.2-15.1-31.7c-16.8-33.8-32.8-65.7-20-92c12.6-26.1,15.7-51.3,15.3-71l12-26   c1.7-3.8,0.1-8.2-3.7-10c-3.8-1.7-8.2-0.1-10,3.7l-1.6,3.5c-1.2-5.9-2.4-9.5-2.6-10c-1.3-3.9-5.6-6-9.5-4.7   c-3.9,1.3-6,5.6-4.7,9.5c0.2,0.5,15.5,48.3-8.8,98.4c-16,33,1.6,68.1,20.1,105.3c14,28.1,28.5,57.2,28,85.6   c-0.7,33.7-10.4,47.5-20.8,62c-9.8,13.9-20,28.2-23.4,57.7c-1.9,16.7-9.2,26.6-21.7,29.4c-21.3,4.7-52.1-12.1-67.2-36.8   c-8-13-14.9-21.1-20.5-27.5c-12-13.9-18-20.9-20.1-61.9C67.4,365.9,63.8,362.7,59.7,362.9L59.7,362.9z\"><\/path>\t\t<path d=\"M70.5,199.3c4.8,37-0.7,55.3-7,76.6c-4.8,16.3-10.3,34.8-11.4,63.4c-0.2,4.1,3.1,7.6,7.2,7.8c0.1,0,0.2,0,0.3,0   c4,0,7.3-3.2,7.5-7.2c1-26.7,5.9-43.5,10.7-59.7c6.5-22,12.7-42.7,7.5-82.8C78.7,146.1,89.3,96,112.2,69.9   c11.5-13,25.6-19.7,41.9-19.7c4.1,0,7.5-3.4,7.5-7.5s-3.4-7.5-7.5-7.5c-20.5,0-38.9,8.6-53.1,24.8   C75.3,89.2,63.3,143.9,70.5,199.3L70.5,199.3z\"><\/path>\t\t<path d=\"M124,116.1c-1.2,1.9-28.8,46.7-8.3,115.4c9.4,31.7,3.1,55.4-3.6,80.4c-6.6,24.4-13.3,49.7-3.5,81.2c1,3.2,4,5.3,7.2,5.3   c0.7,0,1.5-0.1,2.2-0.3c4-1.2,6.2-5.4,4.9-9.4c-8.5-27.3-2.6-49.4,3.7-72.8c7-26,14.2-52.8,3.5-88.6   c-18.4-61.9,6.4-102.7,6.6-103.1c2.2-3.5,1.1-8.1-2.4-10.3C130.8,111.6,126.2,112.6,124,116.1L124,116.1z\"><\/path>\t\t<path d=\"M160.9,470.9c3.3-0.7,5.7-3.5,5.8-6.9c0.5-9.6,4.9-31.6,29.5-64.6c16.3-22,22.5-48.2,17.9-75.7   c-3.4-20.6-11.7-34.7-12.1-35.3c-2.1-3.6-6.7-4.7-10.3-2.6c-3.6,2.1-4.7,6.7-2.6,10.3c0.2,0.3,7.4,12.8,10.3,30.7   c3.8,23.6-1.3,45-15.3,63.7c-26.4,35.5-31.8,60.1-32.5,72.7C151.5,468.2,156,472,160.9,470.9L160.9,470.9z\"><\/path>\t\t<path d=\"M159.6,300.4c-4.1-0.2-7.7,2.9-7.9,7c0,0.3-1.7,27.7-5,46.1c-0.7,4.1,2,8,6.1,8.7c0.4,0.1,0.9,0.1,1.3,0.1   c3.6,0,6.7-2.6,7.4-6.2c3.4-19.2,5.1-46.6,5.2-47.8C166.9,304.2,163.8,300.7,159.6,300.4L159.6,300.4z\"><\/path>\t\t<path d=\"M170.5,81.7c0.1,0.6,5.6,45.5-25.3,76.4c-2.9,2.9-2.9,7.7,0,10.6c1.5,1.5,3.4,2.2,5.3,2.2c1.9,0,3.8-0.7,5.3-2.2   c36.4-36.4,29.9-86.9,29.6-89.1c-0.6-4.1-4.3-7-8.5-6.4C172.8,73.8,170,77.6,170.5,81.7z\"><\/path>\t<\/g><\/g><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Born : 20\/05\/2024<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-cc1a559 elementor-list-item-link-inline elementor-icon-list--layout-traditional elementor-widget elementor-widget-icon-list\" data-id=\"cc1a559\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" id=\"Capa_1\" x=\"0px\" y=\"0px\" viewBox=\"0 0 512 512\" style=\"enable-background:new 0 0 512 512;\" xml:space=\"preserve\"><g>\t<g>\t\t<path d=\"M376.264,290.173c66.314-66.293,66.314-174.16,0-240.453c-66.314-66.294-174.214-66.294-240.529,0   c-66.314,66.293-66.314,174.16,0,240.453c28.07,28.061,63.591,44.24,100.254,48.546v56.923h-40.018   c-11.051,0-20.009,8.956-20.009,20.003s8.958,20.003,20.009,20.003h40.018v56.348c0.001,11.047,8.959,20.003,20.011,20.003   c11.051,0,20.009-8.956,20.009-20.003v-56.348h40.019c11.051,0,20.009-8.956,20.009-20.003s-8.958-20.003-20.009-20.003h-40.019   V338.72C312.673,334.413,348.194,318.234,376.264,290.173z M164.033,261.884c-50.711-50.695-50.711-133.181,0-183.876   c50.71-50.693,133.221-50.696,183.934,0c50.711,50.695,50.711,133.181,0,183.876C297.256,312.578,214.744,312.578,164.033,261.884   z\"><\/path>\t<\/g><\/g><g><\/g><g><\/g><g><\/g><g><\/g><g><\/g><g><\/g><g><\/g><g><\/g><g><\/g><g><\/g><g><\/g><g><\/g><g><\/g><g><\/g><g><\/g><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Lola di Casa Bertolini<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-aa47166 elementor-list-item-link-inline elementor-icon-list--layout-traditional elementor-widget elementor-widget-icon-list\" data-id=\"aa47166\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" height=\"512\" viewBox=\"0 0 64 64\" width=\"512\"><g id=\"_14._Men_sign\" data-name=\"14. Men sign\"><path d=\"m61 5v20.76a2 2 0 0 1 -2 2h-2.62a2 2 0 0 1 -2-2v-11.14c-.02.02-14.42 14.42-14.45 14.44 9.647 13.666-.652 32.711-17.59 31.92a20.323 20.323 0 0 1 -19.32-21.27c.74-15.817 18.86-24.861 31.93-15.66l14.43-14.43h-11.14a2 2 0 0 1 -2-2v-2.62a2 2 0 0 1 2-2h20.76a2 2 0 0 1 2 2zm-24.81 35.69a12.875 12.875 0 1 0 -12.88 12.87 12.884 12.884 0 0 0 12.88-12.87z\" fill=\"#a5ccf2\"><\/path><\/g><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Forever Lohngarten<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-cf6f8b5\" data-id=\"cf6f8b5\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3c12d2b elementor-align-center elementor-mobile-align-left elementor-widget elementor-widget-button\" data-id=\"3c12d2b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.setterirlandese.net\/wp-content\/uploads\/2025\/06\/perla-di-casa-bertolini001-pedigree.pdf\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">PEDIGREE<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7e23286 elementor-align-center elementor-mobile-align-left elementor-widget elementor-widget-button\" data-id=\"7e23286\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.setterirlandese.net\/wp-content\/uploads\/2025\/06\/perla-di-casa-bertolini001-pedigree.pdf\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Hd B Ed O<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-c0e2f07 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"c0e2f07\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-1507b76\" data-id=\"1507b76\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0acbae5 elementor-widget elementor-widget-heading\" data-id=\"0acbae5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">CH Ethel Mrs Star<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-274b644 elementor--h-position-center elementor--v-position-middle elementor-arrows-position-inside elementor-pagination-position-inside elementor-widget elementor-widget-slides\" data-id=\"274b644\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;autoplay_speed&quot;:3000,&quot;navigation&quot;:&quot;both&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;infinite&quot;:&quot;yes&quot;,&quot;transition&quot;:&quot;slide&quot;,&quot;transition_speed&quot;:500}\" data-widget_type=\"slides.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper\">\n\t\t\t\t\t<div class=\"elementor-slides-wrapper elementor-main-swiper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Slides\" dir=\"ltr\" data-animation=\"fadeInUp\">\n\t\t\t\t<div class=\"swiper-wrapper elementor-slides\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-repeater-item-fce16ce swiper-slide\" role=\"group\" aria-roledescription=\"slide\"><div class=\"swiper-slide-bg\" role=\"img\" aria-label=\"etel\"><\/div><div class=\"swiper-slide-inner\" ><div class=\"swiper-slide-contents\"><\/div><\/div><\/div><div class=\"elementor-repeater-item-5d067d5 swiper-slide\" role=\"group\" aria-roledescription=\"slide\"><div class=\"swiper-slide-bg\" role=\"img\" aria-label=\"ethel001\"><\/div><div class=\"swiper-slide-inner\" ><div class=\"swiper-slide-contents\"><\/div><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\" aria-label=\"Previous slide\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-chevron-left\" viewBox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M646 125C629 125 613 133 604 142L308 442C296 454 292 471 292 487 292 504 296 521 308 533L604 854C617 867 629 875 646 875 663 875 679 871 692 858 704 846 713 829 713 812 713 796 708 779 692 767L438 487 692 225C700 217 708 204 708 187 708 171 704 154 692 142 675 129 663 125 646 125Z\"><\/path><\/svg>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\" aria-label=\"Next slide\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-chevron-right\" viewBox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M696 533C708 521 713 504 713 487 713 471 708 454 696 446L400 146C388 133 375 125 354 125 338 125 325 129 313 142 300 154 292 171 292 187 292 204 296 221 308 233L563 492 304 771C292 783 288 800 288 817 288 833 296 850 308 863 321 871 338 875 354 875 371 875 388 867 400 854L696 533Z\"><\/path><\/svg>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-pagination\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-43bbbe2 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"43bbbe2\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-416ecd0\" data-id=\"416ecd0\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e6bbfd7 elementor-list-item-link-inline elementor-icon-list--layout-traditional elementor-widget elementor-widget-icon-list\" data-id=\"e6bbfd7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" id=\"Capa_1\" x=\"0px\" y=\"0px\" viewBox=\"0 0 512 512\" style=\"enable-background:new 0 0 512 512;\" xml:space=\"preserve\"><g>\t<g>\t\t<g>\t\t\t<g>\t\t\t\t<g>\t\t\t\t\t<ellipse cx=\"294.2\" cy=\"103.1\" rx=\"10\" ry=\"12.9\"><\/ellipse>\t\t\t\t<\/g>\t\t\t<\/g>\t\t<\/g>\t<\/g>\t<g>\t\t<path d=\"M16.3,138.1c-2.1,3.6-0.8,8.2,2.8,10.2c1.2,0.7,2.4,1,3.7,1c2.6,0,5.1-1.4,6.5-3.8l43.1-75.8   c14.9-26.1,40.1-45.2,69.3-52.5c13.5-3.3,27.7-3.1,41.1,0.7l34.8,9.8c4,1.1,8.1-1.2,9.3-5.2c1.1-4-1.2-8.1-5.2-9.3l-34.8-9.8   c-15.9-4.5-32.7-4.8-48.8-0.8C105,11,76.3,32.7,59.4,62.4L16.3,138.1L16.3,138.1z\"><\/path>\t\t<path d=\"M493.4,175.4c4-7.6,4.4-16.5,1.1-24.5c-3.3-7.9-9.9-13.9-18.1-16.4L336.5,90.2l-0.9-2.4c-11-29.5-35.7-52.3-66-60.9   l-18.2-5.2c-4-1.1-8.1,1.2-9.3,5.2s1.2,8.1,5.2,9.3l18.2,5.2c25.8,7.3,46.7,26.6,56,51.7l2.2,5.8c0.8,2.2,2.5,3.8,4.7,4.5   l91.9,29.5c-6.2,35.2,4.5,57,14.9,69.2c7,8.2,14.7,13.2,20.1,16l-6.7,19.6c-8.3,24.1-31,40.3-56.4,40.3h-57.5   c-4.1,0-7.5,3.4-7.5,7.5s3.4,7.5,7.5,7.5h57.5c31.9,0,60.3-20.3,70.6-50.4l8.5-24.7L493.4,175.4z M461.3,204.3   c-11-5.9-33.3-23.6-26.5-66.9l37.2,11.4c3.9,1.2,7.1,4.1,8.7,7.9c1.6,3.8,1.4,8.1-0.5,11.7L461.3,204.3L461.3,204.3z\"><\/path>\t\t<path d=\"M59.7,362.9c-4.1,0.2-7.3,3.7-7.1,7.9c2.2,44.1,9.6,54.7,23.7,70.9c5.5,6.4,11.7,13.6,19.1,25.6   c16.2,26.4,46.9,44.7,72.7,44.7c3.6,0,7.1-0.4,10.5-1.1c10.9-2.4,29.8-11.1,33.3-42.3c2.9-25.6,11.6-37.8,20.7-50.7   c11.2-15.8,22.8-32.1,23.5-70.4c0.3-16-3.3-31.6-8.9-47c10.7-5,22.7-7.6,34.7-7.6h23.8c4.1,0,7.5-3.4,7.5-7.5s-3.4-7.5-7.5-7.5   H282c-14,0-27.8,3-40.3,8.6c-4.6-10.7-9.9-21.2-15.1-31.7c-16.8-33.8-32.8-65.7-20-92c12.6-26.1,15.7-51.3,15.3-71l12-26   c1.7-3.8,0.1-8.2-3.7-10c-3.8-1.7-8.2-0.1-10,3.7l-1.6,3.5c-1.2-5.9-2.4-9.5-2.6-10c-1.3-3.9-5.6-6-9.5-4.7   c-3.9,1.3-6,5.6-4.7,9.5c0.2,0.5,15.5,48.3-8.8,98.4c-16,33,1.6,68.1,20.1,105.3c14,28.1,28.5,57.2,28,85.6   c-0.7,33.7-10.4,47.5-20.8,62c-9.8,13.9-20,28.2-23.4,57.7c-1.9,16.7-9.2,26.6-21.7,29.4c-21.3,4.7-52.1-12.1-67.2-36.8   c-8-13-14.9-21.1-20.5-27.5c-12-13.9-18-20.9-20.1-61.9C67.4,365.9,63.8,362.7,59.7,362.9L59.7,362.9z\"><\/path>\t\t<path d=\"M70.5,199.3c4.8,37-0.7,55.3-7,76.6c-4.8,16.3-10.3,34.8-11.4,63.4c-0.2,4.1,3.1,7.6,7.2,7.8c0.1,0,0.2,0,0.3,0   c4,0,7.3-3.2,7.5-7.2c1-26.7,5.9-43.5,10.7-59.7c6.5-22,12.7-42.7,7.5-82.8C78.7,146.1,89.3,96,112.2,69.9   c11.5-13,25.6-19.7,41.9-19.7c4.1,0,7.5-3.4,7.5-7.5s-3.4-7.5-7.5-7.5c-20.5,0-38.9,8.6-53.1,24.8   C75.3,89.2,63.3,143.9,70.5,199.3L70.5,199.3z\"><\/path>\t\t<path d=\"M124,116.1c-1.2,1.9-28.8,46.7-8.3,115.4c9.4,31.7,3.1,55.4-3.6,80.4c-6.6,24.4-13.3,49.7-3.5,81.2c1,3.2,4,5.3,7.2,5.3   c0.7,0,1.5-0.1,2.2-0.3c4-1.2,6.2-5.4,4.9-9.4c-8.5-27.3-2.6-49.4,3.7-72.8c7-26,14.2-52.8,3.5-88.6   c-18.4-61.9,6.4-102.7,6.6-103.1c2.2-3.5,1.1-8.1-2.4-10.3C130.8,111.6,126.2,112.6,124,116.1L124,116.1z\"><\/path>\t\t<path d=\"M160.9,470.9c3.3-0.7,5.7-3.5,5.8-6.9c0.5-9.6,4.9-31.6,29.5-64.6c16.3-22,22.5-48.2,17.9-75.7   c-3.4-20.6-11.7-34.7-12.1-35.3c-2.1-3.6-6.7-4.7-10.3-2.6c-3.6,2.1-4.7,6.7-2.6,10.3c0.2,0.3,7.4,12.8,10.3,30.7   c3.8,23.6-1.3,45-15.3,63.7c-26.4,35.5-31.8,60.1-32.5,72.7C151.5,468.2,156,472,160.9,470.9L160.9,470.9z\"><\/path>\t\t<path d=\"M159.6,300.4c-4.1-0.2-7.7,2.9-7.9,7c0,0.3-1.7,27.7-5,46.1c-0.7,4.1,2,8,6.1,8.7c0.4,0.1,0.9,0.1,1.3,0.1   c3.6,0,6.7-2.6,7.4-6.2c3.4-19.2,5.1-46.6,5.2-47.8C166.9,304.2,163.8,300.7,159.6,300.4L159.6,300.4z\"><\/path>\t\t<path d=\"M170.5,81.7c0.1,0.6,5.6,45.5-25.3,76.4c-2.9,2.9-2.9,7.7,0,10.6c1.5,1.5,3.4,2.2,5.3,2.2c1.9,0,3.8-0.7,5.3-2.2   c36.4-36.4,29.9-86.9,29.6-89.1c-0.6-4.1-4.3-7-8.5-6.4C172.8,73.8,170,77.6,170.5,81.7z\"><\/path>\t<\/g><\/g><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Born : 31\/01\/2015<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1b11742 elementor-list-item-link-inline elementor-icon-list--layout-traditional elementor-widget elementor-widget-icon-list\" data-id=\"1b11742\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" id=\"Capa_1\" x=\"0px\" y=\"0px\" viewBox=\"0 0 512 512\" style=\"enable-background:new 0 0 512 512;\" xml:space=\"preserve\"><g>\t<g>\t\t<path d=\"M376.264,290.173c66.314-66.293,66.314-174.16,0-240.453c-66.314-66.294-174.214-66.294-240.529,0   c-66.314,66.293-66.314,174.16,0,240.453c28.07,28.061,63.591,44.24,100.254,48.546v56.923h-40.018   c-11.051,0-20.009,8.956-20.009,20.003s8.958,20.003,20.009,20.003h40.018v56.348c0.001,11.047,8.959,20.003,20.011,20.003   c11.051,0,20.009-8.956,20.009-20.003v-56.348h40.019c11.051,0,20.009-8.956,20.009-20.003s-8.958-20.003-20.009-20.003h-40.019   V338.72C312.673,334.413,348.194,318.234,376.264,290.173z M164.033,261.884c-50.711-50.695-50.711-133.181,0-183.876   c50.71-50.693,133.221-50.696,183.934,0c50.711,50.695,50.711,133.181,0,183.876C297.256,312.578,214.744,312.578,164.033,261.884   z\"><\/path>\t<\/g><\/g><g><\/g><g><\/g><g><\/g><g><\/g><g><\/g><g><\/g><g><\/g><g><\/g><g><\/g><g><\/g><g><\/g><g><\/g><g><\/g><g><\/g><g><\/g><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Darleene della Mezza Luna<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-73c59e1 elementor-list-item-link-inline elementor-icon-list--layout-traditional elementor-widget elementor-widget-icon-list\" data-id=\"73c59e1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" height=\"512\" viewBox=\"0 0 64 64\" width=\"512\"><g id=\"_14._Men_sign\" data-name=\"14. Men sign\"><path d=\"m61 5v20.76a2 2 0 0 1 -2 2h-2.62a2 2 0 0 1 -2-2v-11.14c-.02.02-14.42 14.42-14.45 14.44 9.647 13.666-.652 32.711-17.59 31.92a20.323 20.323 0 0 1 -19.32-21.27c.74-15.817 18.86-24.861 31.93-15.66l14.43-14.43h-11.14a2 2 0 0 1 -2-2v-2.62a2 2 0 0 1 2-2h20.76a2 2 0 0 1 2 2zm-24.81 35.69a12.875 12.875 0 1 0 -12.88 12.87 12.884 12.884 0 0 0 12.88-12.87z\" fill=\"#a5ccf2\"><\/path><\/g><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Garden Star's Rolling Stone<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-33dfb80\" data-id=\"33dfb80\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2dfa60d elementor-align-center elementor-mobile-align-left elementor-widget elementor-widget-button\" data-id=\"2dfa60d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.setterirlandese.net\/wp-content\/uploads\/2022\/03\/pedigree-ethel-mrs-star.pdf\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">PEDIGREE<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f0476a0 elementor-align-center elementor-mobile-align-left elementor-widget elementor-widget-button\" data-id=\"f0476a0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"http:\/\/setterirlandese.net\/wp-content\/uploads\/2022\/03\/campione.pdf\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">CAMPIONE<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-1d59e1e\" data-id=\"1d59e1e\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2eb40f7 elementor-widget elementor-widget-heading\" data-id=\"2eb40f7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Summer Dream<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-07b50ab elementor--h-position-center elementor--v-position-middle elementor-arrows-position-inside elementor-pagination-position-inside elementor-widget elementor-widget-slides\" data-id=\"07b50ab\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;autoplay_speed&quot;:3000,&quot;navigation&quot;:&quot;both&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;infinite&quot;:&quot;yes&quot;,&quot;transition&quot;:&quot;slide&quot;,&quot;transition_speed&quot;:500}\" data-widget_type=\"slides.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper\">\n\t\t\t\t\t<div class=\"elementor-slides-wrapper elementor-main-swiper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Slides\" dir=\"ltr\" data-animation=\"fadeInUp\">\n\t\t\t\t<div class=\"swiper-wrapper elementor-slides\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-repeater-item-9e2baa6 swiper-slide\" role=\"group\" aria-roledescription=\"slide\"><div class=\"swiper-slide-bg\" role=\"img\" aria-label=\"setter-irlandese-femmina002\"><\/div><div class=\"swiper-slide-inner\" ><div class=\"swiper-slide-contents\"><\/div><\/div><\/div><div class=\"elementor-repeater-item-5f96d07 swiper-slide\" role=\"group\" aria-roledescription=\"slide\"><div class=\"swiper-slide-bg\" role=\"img\" aria-label=\"setter-irlandese-femmina001\"><\/div><div class=\"swiper-slide-inner\" ><div class=\"swiper-slide-contents\"><\/div><\/div><\/div><div class=\"elementor-repeater-item-b0b678d swiper-slide\" role=\"group\" aria-roledescription=\"slide\"><div class=\"swiper-slide-bg\" role=\"img\" aria-label=\"summer-dream001\"><\/div><div class=\"swiper-slide-inner\" ><div class=\"swiper-slide-contents\"><\/div><\/div><\/div><div class=\"elementor-repeater-item-20af28c swiper-slide\" role=\"group\" aria-roledescription=\"slide\"><div class=\"swiper-slide-bg\" role=\"img\" aria-label=\"summer-dream002\"><\/div><div class=\"swiper-slide-inner\" ><div class=\"swiper-slide-contents\"><\/div><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\" aria-label=\"Previous slide\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-chevron-left\" viewBox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M646 125C629 125 613 133 604 142L308 442C296 454 292 471 292 487 292 504 296 521 308 533L604 854C617 867 629 875 646 875 663 875 679 871 692 858 704 846 713 829 713 812 713 796 708 779 692 767L438 487 692 225C700 217 708 204 708 187 708 171 704 154 692 142 675 129 663 125 646 125Z\"><\/path><\/svg>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\" aria-label=\"Next slide\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-chevron-right\" viewBox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M696 533C708 521 713 504 713 487 713 471 708 454 696 446L400 146C388 133 375 125 354 125 338 125 325 129 313 142 300 154 292 171 292 187 292 204 296 221 308 233L563 492 304 771C292 783 288 800 288 817 288 833 296 850 308 863 321 871 338 875 354 875 371 875 388 867 400 854L696 533Z\"><\/path><\/svg>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-pagination\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-9dc4594 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"9dc4594\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-bcf91cf\" data-id=\"bcf91cf\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-74392ca elementor-list-item-link-inline elementor-icon-list--layout-traditional elementor-widget elementor-widget-icon-list\" data-id=\"74392ca\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" id=\"Capa_1\" x=\"0px\" y=\"0px\" viewBox=\"0 0 512 512\" style=\"enable-background:new 0 0 512 512;\" xml:space=\"preserve\"><g>\t<g>\t\t<g>\t\t\t<g>\t\t\t\t<g>\t\t\t\t\t<ellipse cx=\"294.2\" cy=\"103.1\" rx=\"10\" ry=\"12.9\"><\/ellipse>\t\t\t\t<\/g>\t\t\t<\/g>\t\t<\/g>\t<\/g>\t<g>\t\t<path d=\"M16.3,138.1c-2.1,3.6-0.8,8.2,2.8,10.2c1.2,0.7,2.4,1,3.7,1c2.6,0,5.1-1.4,6.5-3.8l43.1-75.8   c14.9-26.1,40.1-45.2,69.3-52.5c13.5-3.3,27.7-3.1,41.1,0.7l34.8,9.8c4,1.1,8.1-1.2,9.3-5.2c1.1-4-1.2-8.1-5.2-9.3l-34.8-9.8   c-15.9-4.5-32.7-4.8-48.8-0.8C105,11,76.3,32.7,59.4,62.4L16.3,138.1L16.3,138.1z\"><\/path>\t\t<path d=\"M493.4,175.4c4-7.6,4.4-16.5,1.1-24.5c-3.3-7.9-9.9-13.9-18.1-16.4L336.5,90.2l-0.9-2.4c-11-29.5-35.7-52.3-66-60.9   l-18.2-5.2c-4-1.1-8.1,1.2-9.3,5.2s1.2,8.1,5.2,9.3l18.2,5.2c25.8,7.3,46.7,26.6,56,51.7l2.2,5.8c0.8,2.2,2.5,3.8,4.7,4.5   l91.9,29.5c-6.2,35.2,4.5,57,14.9,69.2c7,8.2,14.7,13.2,20.1,16l-6.7,19.6c-8.3,24.1-31,40.3-56.4,40.3h-57.5   c-4.1,0-7.5,3.4-7.5,7.5s3.4,7.5,7.5,7.5h57.5c31.9,0,60.3-20.3,70.6-50.4l8.5-24.7L493.4,175.4z M461.3,204.3   c-11-5.9-33.3-23.6-26.5-66.9l37.2,11.4c3.9,1.2,7.1,4.1,8.7,7.9c1.6,3.8,1.4,8.1-0.5,11.7L461.3,204.3L461.3,204.3z\"><\/path>\t\t<path d=\"M59.7,362.9c-4.1,0.2-7.3,3.7-7.1,7.9c2.2,44.1,9.6,54.7,23.7,70.9c5.5,6.4,11.7,13.6,19.1,25.6   c16.2,26.4,46.9,44.7,72.7,44.7c3.6,0,7.1-0.4,10.5-1.1c10.9-2.4,29.8-11.1,33.3-42.3c2.9-25.6,11.6-37.8,20.7-50.7   c11.2-15.8,22.8-32.1,23.5-70.4c0.3-16-3.3-31.6-8.9-47c10.7-5,22.7-7.6,34.7-7.6h23.8c4.1,0,7.5-3.4,7.5-7.5s-3.4-7.5-7.5-7.5   H282c-14,0-27.8,3-40.3,8.6c-4.6-10.7-9.9-21.2-15.1-31.7c-16.8-33.8-32.8-65.7-20-92c12.6-26.1,15.7-51.3,15.3-71l12-26   c1.7-3.8,0.1-8.2-3.7-10c-3.8-1.7-8.2-0.1-10,3.7l-1.6,3.5c-1.2-5.9-2.4-9.5-2.6-10c-1.3-3.9-5.6-6-9.5-4.7   c-3.9,1.3-6,5.6-4.7,9.5c0.2,0.5,15.5,48.3-8.8,98.4c-16,33,1.6,68.1,20.1,105.3c14,28.1,28.5,57.2,28,85.6   c-0.7,33.7-10.4,47.5-20.8,62c-9.8,13.9-20,28.2-23.4,57.7c-1.9,16.7-9.2,26.6-21.7,29.4c-21.3,4.7-52.1-12.1-67.2-36.8   c-8-13-14.9-21.1-20.5-27.5c-12-13.9-18-20.9-20.1-61.9C67.4,365.9,63.8,362.7,59.7,362.9L59.7,362.9z\"><\/path>\t\t<path d=\"M70.5,199.3c4.8,37-0.7,55.3-7,76.6c-4.8,16.3-10.3,34.8-11.4,63.4c-0.2,4.1,3.1,7.6,7.2,7.8c0.1,0,0.2,0,0.3,0   c4,0,7.3-3.2,7.5-7.2c1-26.7,5.9-43.5,10.7-59.7c6.5-22,12.7-42.7,7.5-82.8C78.7,146.1,89.3,96,112.2,69.9   c11.5-13,25.6-19.7,41.9-19.7c4.1,0,7.5-3.4,7.5-7.5s-3.4-7.5-7.5-7.5c-20.5,0-38.9,8.6-53.1,24.8   C75.3,89.2,63.3,143.9,70.5,199.3L70.5,199.3z\"><\/path>\t\t<path d=\"M124,116.1c-1.2,1.9-28.8,46.7-8.3,115.4c9.4,31.7,3.1,55.4-3.6,80.4c-6.6,24.4-13.3,49.7-3.5,81.2c1,3.2,4,5.3,7.2,5.3   c0.7,0,1.5-0.1,2.2-0.3c4-1.2,6.2-5.4,4.9-9.4c-8.5-27.3-2.6-49.4,3.7-72.8c7-26,14.2-52.8,3.5-88.6   c-18.4-61.9,6.4-102.7,6.6-103.1c2.2-3.5,1.1-8.1-2.4-10.3C130.8,111.6,126.2,112.6,124,116.1L124,116.1z\"><\/path>\t\t<path d=\"M160.9,470.9c3.3-0.7,5.7-3.5,5.8-6.9c0.5-9.6,4.9-31.6,29.5-64.6c16.3-22,22.5-48.2,17.9-75.7   c-3.4-20.6-11.7-34.7-12.1-35.3c-2.1-3.6-6.7-4.7-10.3-2.6c-3.6,2.1-4.7,6.7-2.6,10.3c0.2,0.3,7.4,12.8,10.3,30.7   c3.8,23.6-1.3,45-15.3,63.7c-26.4,35.5-31.8,60.1-32.5,72.7C151.5,468.2,156,472,160.9,470.9L160.9,470.9z\"><\/path>\t\t<path d=\"M159.6,300.4c-4.1-0.2-7.7,2.9-7.9,7c0,0.3-1.7,27.7-5,46.1c-0.7,4.1,2,8,6.1,8.7c0.4,0.1,0.9,0.1,1.3,0.1   c3.6,0,6.7-2.6,7.4-6.2c3.4-19.2,5.1-46.6,5.2-47.8C166.9,304.2,163.8,300.7,159.6,300.4L159.6,300.4z\"><\/path>\t\t<path d=\"M170.5,81.7c0.1,0.6,5.6,45.5-25.3,76.4c-2.9,2.9-2.9,7.7,0,10.6c1.5,1.5,3.4,2.2,5.3,2.2c1.9,0,3.8-0.7,5.3-2.2   c36.4-36.4,29.9-86.9,29.6-89.1c-0.6-4.1-4.3-7-8.5-6.4C172.8,73.8,170,77.6,170.5,81.7z\"><\/path>\t<\/g><\/g><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Born : 06\/04\/2019<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-344fc7b elementor-list-item-link-inline elementor-icon-list--layout-traditional elementor-widget elementor-widget-icon-list\" data-id=\"344fc7b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" id=\"Capa_1\" x=\"0px\" y=\"0px\" viewBox=\"0 0 512 512\" style=\"enable-background:new 0 0 512 512;\" xml:space=\"preserve\"><g>\t<g>\t\t<path d=\"M376.264,290.173c66.314-66.293,66.314-174.16,0-240.453c-66.314-66.294-174.214-66.294-240.529,0   c-66.314,66.293-66.314,174.16,0,240.453c28.07,28.061,63.591,44.24,100.254,48.546v56.923h-40.018   c-11.051,0-20.009,8.956-20.009,20.003s8.958,20.003,20.009,20.003h40.018v56.348c0.001,11.047,8.959,20.003,20.011,20.003   c11.051,0,20.009-8.956,20.009-20.003v-56.348h40.019c11.051,0,20.009-8.956,20.009-20.003s-8.958-20.003-20.009-20.003h-40.019   V338.72C312.673,334.413,348.194,318.234,376.264,290.173z M164.033,261.884c-50.711-50.695-50.711-133.181,0-183.876   c50.71-50.693,133.221-50.696,183.934,0c50.711,50.695,50.711,133.181,0,183.876C297.256,312.578,214.744,312.578,164.033,261.884   z\"><\/path>\t<\/g><\/g><g><\/g><g><\/g><g><\/g><g><\/g><g><\/g><g><\/g><g><\/g><g><\/g><g><\/g><g><\/g><g><\/g><g><\/g><g><\/g><g><\/g><g><\/g><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Thendara London Look<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-eccec02 elementor-list-item-link-inline elementor-icon-list--layout-traditional elementor-widget elementor-widget-icon-list\" data-id=\"eccec02\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" height=\"512\" viewBox=\"0 0 64 64\" width=\"512\"><g id=\"_14._Men_sign\" data-name=\"14. Men sign\"><path d=\"m61 5v20.76a2 2 0 0 1 -2 2h-2.62a2 2 0 0 1 -2-2v-11.14c-.02.02-14.42 14.42-14.45 14.44 9.647 13.666-.652 32.711-17.59 31.92a20.323 20.323 0 0 1 -19.32-21.27c.74-15.817 18.86-24.861 31.93-15.66l14.43-14.43h-11.14a2 2 0 0 1 -2-2v-2.62a2 2 0 0 1 2-2h20.76a2 2 0 0 1 2 2zm-24.81 35.69a12.875 12.875 0 1 0 -12.88 12.87 12.884 12.884 0 0 0 12.88-12.87z\" fill=\"#a5ccf2\"><\/path><\/g><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">You Are The Best<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-db6acfd\" data-id=\"db6acfd\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-01ad318 elementor-align-center elementor-mobile-align-left elementor-widget elementor-widget-button\" data-id=\"01ad318\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.setterirlandese.net\/wp-content\/uploads\/2022\/03\/summer-dream-pedigree.pdf\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">PEDIGREE<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3e2b575 elementor-align-center elementor-mobile-align-left elementor-widget elementor-widget-button\" data-id=\"3e2b575\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"http:\/\/setterirlandese.net\/wp-content\/uploads\/2022\/03\/Hd-A-Ed-O-1.pdf\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Hd A Ed O<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2330abc elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2330abc\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-f90d6c9\" data-id=\"f90d6c9\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-bd59979 elementor-widget elementor-widget-heading\" data-id=\"bd59979\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Red Blossom<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-96c28da elementor--h-position-center elementor--v-position-middle elementor-arrows-position-inside elementor-pagination-position-inside elementor-widget elementor-widget-slides\" data-id=\"96c28da\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;autoplay_speed&quot;:3000,&quot;navigation&quot;:&quot;both&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;infinite&quot;:&quot;yes&quot;,&quot;transition&quot;:&quot;slide&quot;,&quot;transition_speed&quot;:500}\" data-widget_type=\"slides.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper\">\n\t\t\t\t\t<div class=\"elementor-slides-wrapper elementor-main-swiper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Slides\" dir=\"ltr\" data-animation=\"fadeInUp\">\n\t\t\t\t<div class=\"swiper-wrapper elementor-slides\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-repeater-item-5d067d5 swiper-slide\" role=\"group\" aria-roledescription=\"slide\"><div class=\"swiper-slide-bg\" role=\"img\" aria-label=\"redbloccom002\"><\/div><div class=\"swiper-slide-inner\" ><div class=\"swiper-slide-contents\"><\/div><\/div><\/div><div class=\"elementor-repeater-item-4c17266 swiper-slide\" role=\"group\" aria-roledescription=\"slide\"><div class=\"swiper-slide-bg\" role=\"img\" aria-label=\"redblossom005\"><\/div><div class=\"swiper-slide-inner\" ><div class=\"swiper-slide-contents\"><\/div><\/div><\/div><div class=\"elementor-repeater-item-fce16ce swiper-slide\" role=\"group\" aria-roledescription=\"slide\"><div class=\"swiper-slide-bg\" role=\"img\" aria-label=\"001\"><\/div><div class=\"swiper-slide-inner\" ><div class=\"swiper-slide-contents\"><\/div><\/div><\/div><div class=\"elementor-repeater-item-c5790dc swiper-slide\" role=\"group\" aria-roledescription=\"slide\"><div class=\"swiper-slide-bg\" role=\"img\" aria-label=\"001\"><\/div><div class=\"swiper-slide-inner\" ><div class=\"swiper-slide-contents\"><\/div><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\" aria-label=\"Previous slide\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-chevron-left\" viewBox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M646 125C629 125 613 133 604 142L308 442C296 454 292 471 292 487 292 504 296 521 308 533L604 854C617 867 629 875 646 875 663 875 679 871 692 858 704 846 713 829 713 812 713 796 708 779 692 767L438 487 692 225C700 217 708 204 708 187 708 171 704 154 692 142 675 129 663 125 646 125Z\"><\/path><\/svg>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\" aria-label=\"Next slide\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-chevron-right\" viewBox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M696 533C708 521 713 504 713 487 713 471 708 454 696 446L400 146C388 133 375 125 354 125 338 125 325 129 313 142 300 154 292 171 292 187 292 204 296 221 308 233L563 492 304 771C292 783 288 800 288 817 288 833 296 850 308 863 321 871 338 875 354 875 371 875 388 867 400 854L696 533Z\"><\/path><\/svg>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-pagination\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-35e4022 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"35e4022\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-8a1ede8\" data-id=\"8a1ede8\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-43d7456 elementor-list-item-link-inline elementor-icon-list--layout-traditional elementor-widget elementor-widget-icon-list\" data-id=\"43d7456\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" id=\"Capa_1\" x=\"0px\" y=\"0px\" viewBox=\"0 0 512 512\" style=\"enable-background:new 0 0 512 512;\" xml:space=\"preserve\"><g>\t<g>\t\t<g>\t\t\t<g>\t\t\t\t<g>\t\t\t\t\t<ellipse cx=\"294.2\" cy=\"103.1\" rx=\"10\" ry=\"12.9\"><\/ellipse>\t\t\t\t<\/g>\t\t\t<\/g>\t\t<\/g>\t<\/g>\t<g>\t\t<path d=\"M16.3,138.1c-2.1,3.6-0.8,8.2,2.8,10.2c1.2,0.7,2.4,1,3.7,1c2.6,0,5.1-1.4,6.5-3.8l43.1-75.8   c14.9-26.1,40.1-45.2,69.3-52.5c13.5-3.3,27.7-3.1,41.1,0.7l34.8,9.8c4,1.1,8.1-1.2,9.3-5.2c1.1-4-1.2-8.1-5.2-9.3l-34.8-9.8   c-15.9-4.5-32.7-4.8-48.8-0.8C105,11,76.3,32.7,59.4,62.4L16.3,138.1L16.3,138.1z\"><\/path>\t\t<path d=\"M493.4,175.4c4-7.6,4.4-16.5,1.1-24.5c-3.3-7.9-9.9-13.9-18.1-16.4L336.5,90.2l-0.9-2.4c-11-29.5-35.7-52.3-66-60.9   l-18.2-5.2c-4-1.1-8.1,1.2-9.3,5.2s1.2,8.1,5.2,9.3l18.2,5.2c25.8,7.3,46.7,26.6,56,51.7l2.2,5.8c0.8,2.2,2.5,3.8,4.7,4.5   l91.9,29.5c-6.2,35.2,4.5,57,14.9,69.2c7,8.2,14.7,13.2,20.1,16l-6.7,19.6c-8.3,24.1-31,40.3-56.4,40.3h-57.5   c-4.1,0-7.5,3.4-7.5,7.5s3.4,7.5,7.5,7.5h57.5c31.9,0,60.3-20.3,70.6-50.4l8.5-24.7L493.4,175.4z M461.3,204.3   c-11-5.9-33.3-23.6-26.5-66.9l37.2,11.4c3.9,1.2,7.1,4.1,8.7,7.9c1.6,3.8,1.4,8.1-0.5,11.7L461.3,204.3L461.3,204.3z\"><\/path>\t\t<path d=\"M59.7,362.9c-4.1,0.2-7.3,3.7-7.1,7.9c2.2,44.1,9.6,54.7,23.7,70.9c5.5,6.4,11.7,13.6,19.1,25.6   c16.2,26.4,46.9,44.7,72.7,44.7c3.6,0,7.1-0.4,10.5-1.1c10.9-2.4,29.8-11.1,33.3-42.3c2.9-25.6,11.6-37.8,20.7-50.7   c11.2-15.8,22.8-32.1,23.5-70.4c0.3-16-3.3-31.6-8.9-47c10.7-5,22.7-7.6,34.7-7.6h23.8c4.1,0,7.5-3.4,7.5-7.5s-3.4-7.5-7.5-7.5   H282c-14,0-27.8,3-40.3,8.6c-4.6-10.7-9.9-21.2-15.1-31.7c-16.8-33.8-32.8-65.7-20-92c12.6-26.1,15.7-51.3,15.3-71l12-26   c1.7-3.8,0.1-8.2-3.7-10c-3.8-1.7-8.2-0.1-10,3.7l-1.6,3.5c-1.2-5.9-2.4-9.5-2.6-10c-1.3-3.9-5.6-6-9.5-4.7   c-3.9,1.3-6,5.6-4.7,9.5c0.2,0.5,15.5,48.3-8.8,98.4c-16,33,1.6,68.1,20.1,105.3c14,28.1,28.5,57.2,28,85.6   c-0.7,33.7-10.4,47.5-20.8,62c-9.8,13.9-20,28.2-23.4,57.7c-1.9,16.7-9.2,26.6-21.7,29.4c-21.3,4.7-52.1-12.1-67.2-36.8   c-8-13-14.9-21.1-20.5-27.5c-12-13.9-18-20.9-20.1-61.9C67.4,365.9,63.8,362.7,59.7,362.9L59.7,362.9z\"><\/path>\t\t<path d=\"M70.5,199.3c4.8,37-0.7,55.3-7,76.6c-4.8,16.3-10.3,34.8-11.4,63.4c-0.2,4.1,3.1,7.6,7.2,7.8c0.1,0,0.2,0,0.3,0   c4,0,7.3-3.2,7.5-7.2c1-26.7,5.9-43.5,10.7-59.7c6.5-22,12.7-42.7,7.5-82.8C78.7,146.1,89.3,96,112.2,69.9   c11.5-13,25.6-19.7,41.9-19.7c4.1,0,7.5-3.4,7.5-7.5s-3.4-7.5-7.5-7.5c-20.5,0-38.9,8.6-53.1,24.8   C75.3,89.2,63.3,143.9,70.5,199.3L70.5,199.3z\"><\/path>\t\t<path d=\"M124,116.1c-1.2,1.9-28.8,46.7-8.3,115.4c9.4,31.7,3.1,55.4-3.6,80.4c-6.6,24.4-13.3,49.7-3.5,81.2c1,3.2,4,5.3,7.2,5.3   c0.7,0,1.5-0.1,2.2-0.3c4-1.2,6.2-5.4,4.9-9.4c-8.5-27.3-2.6-49.4,3.7-72.8c7-26,14.2-52.8,3.5-88.6   c-18.4-61.9,6.4-102.7,6.6-103.1c2.2-3.5,1.1-8.1-2.4-10.3C130.8,111.6,126.2,112.6,124,116.1L124,116.1z\"><\/path>\t\t<path d=\"M160.9,470.9c3.3-0.7,5.7-3.5,5.8-6.9c0.5-9.6,4.9-31.6,29.5-64.6c16.3-22,22.5-48.2,17.9-75.7   c-3.4-20.6-11.7-34.7-12.1-35.3c-2.1-3.6-6.7-4.7-10.3-2.6c-3.6,2.1-4.7,6.7-2.6,10.3c0.2,0.3,7.4,12.8,10.3,30.7   c3.8,23.6-1.3,45-15.3,63.7c-26.4,35.5-31.8,60.1-32.5,72.7C151.5,468.2,156,472,160.9,470.9L160.9,470.9z\"><\/path>\t\t<path d=\"M159.6,300.4c-4.1-0.2-7.7,2.9-7.9,7c0,0.3-1.7,27.7-5,46.1c-0.7,4.1,2,8,6.1,8.7c0.4,0.1,0.9,0.1,1.3,0.1   c3.6,0,6.7-2.6,7.4-6.2c3.4-19.2,5.1-46.6,5.2-47.8C166.9,304.2,163.8,300.7,159.6,300.4L159.6,300.4z\"><\/path>\t\t<path d=\"M170.5,81.7c0.1,0.6,5.6,45.5-25.3,76.4c-2.9,2.9-2.9,7.7,0,10.6c1.5,1.5,3.4,2.2,5.3,2.2c1.9,0,3.8-0.7,5.3-2.2   c36.4-36.4,29.9-86.9,29.6-89.1c-0.6-4.1-4.3-7-8.5-6.4C172.8,73.8,170,77.6,170.5,81.7z\"><\/path>\t<\/g><\/g><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Born: 06\/04\/2019<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f91b925 elementor-list-item-link-inline elementor-icon-list--layout-traditional elementor-widget elementor-widget-icon-list\" data-id=\"f91b925\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" id=\"Capa_1\" x=\"0px\" y=\"0px\" viewBox=\"0 0 512 512\" style=\"enable-background:new 0 0 512 512;\" xml:space=\"preserve\"><g>\t<g>\t\t<path d=\"M376.264,290.173c66.314-66.293,66.314-174.16,0-240.453c-66.314-66.294-174.214-66.294-240.529,0   c-66.314,66.293-66.314,174.16,0,240.453c28.07,28.061,63.591,44.24,100.254,48.546v56.923h-40.018   c-11.051,0-20.009,8.956-20.009,20.003s8.958,20.003,20.009,20.003h40.018v56.348c0.001,11.047,8.959,20.003,20.011,20.003   c11.051,0,20.009-8.956,20.009-20.003v-56.348h40.019c11.051,0,20.009-8.956,20.009-20.003s-8.958-20.003-20.009-20.003h-40.019   V338.72C312.673,334.413,348.194,318.234,376.264,290.173z M164.033,261.884c-50.711-50.695-50.711-133.181,0-183.876   c50.71-50.693,133.221-50.696,183.934,0c50.711,50.695,50.711,133.181,0,183.876C297.256,312.578,214.744,312.578,164.033,261.884   z\"><\/path>\t<\/g><\/g><g><\/g><g><\/g><g><\/g><g><\/g><g><\/g><g><\/g><g><\/g><g><\/g><g><\/g><g><\/g><g><\/g><g><\/g><g><\/g><g><\/g><g><\/g><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Thendara London Look<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0703539 elementor-list-item-link-inline elementor-icon-list--layout-traditional elementor-widget elementor-widget-icon-list\" data-id=\"0703539\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" height=\"512\" viewBox=\"0 0 64 64\" width=\"512\"><g id=\"_14._Men_sign\" data-name=\"14. Men sign\"><path d=\"m61 5v20.76a2 2 0 0 1 -2 2h-2.62a2 2 0 0 1 -2-2v-11.14c-.02.02-14.42 14.42-14.45 14.44 9.647 13.666-.652 32.711-17.59 31.92a20.323 20.323 0 0 1 -19.32-21.27c.74-15.817 18.86-24.861 31.93-15.66l14.43-14.43h-11.14a2 2 0 0 1 -2-2v-2.62a2 2 0 0 1 2-2h20.76a2 2 0 0 1 2 2zm-24.81 35.69a12.875 12.875 0 1 0 -12.88 12.87 12.884 12.884 0 0 0 12.88-12.87z\" fill=\"#a5ccf2\"><\/path><\/g><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">You Are The Best<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-b9f88a6\" data-id=\"b9f88a6\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5ee4b40 elementor-align-center elementor-mobile-align-left elementor-widget elementor-widget-button\" data-id=\"5ee4b40\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.setterirlandese.net\/wp-content\/uploads\/2022\/03\/pedigree-red-blossom.pdf\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">PEDIGREE<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b28817d elementor-align-center elementor-mobile-align-left elementor-widget elementor-widget-button\" data-id=\"b28817d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"http:\/\/setterirlandese.net\/wp-content\/uploads\/2022\/03\/Hd-A-Ed-O-3.pdf\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Hd A Ed O<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-4a0920d\" data-id=\"4a0920d\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-81b596a elementor-widget elementor-widget-heading\" data-id=\"81b596a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Dee Dee Bee<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ce49366 elementor--h-position-center elementor--v-position-middle elementor-arrows-position-inside elementor-pagination-position-inside elementor-widget elementor-widget-slides\" data-id=\"ce49366\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;autoplay_speed&quot;:3000,&quot;navigation&quot;:&quot;both&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;infinite&quot;:&quot;yes&quot;,&quot;transition&quot;:&quot;slide&quot;,&quot;transition_speed&quot;:500}\" data-widget_type=\"slides.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper\">\n\t\t\t\t\t<div class=\"elementor-slides-wrapper elementor-main-swiper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Slides\" dir=\"ltr\" data-animation=\"fadeInUp\">\n\t\t\t\t<div class=\"swiper-wrapper elementor-slides\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-repeater-item-265e9d1 swiper-slide\" role=\"group\" aria-roledescription=\"slide\"><div class=\"swiper-slide-bg\" role=\"img\" aria-label=\"dee-dee-bee-1003\"><\/div><div class=\"swiper-slide-inner\" ><div class=\"swiper-slide-contents\"><\/div><\/div><\/div><div class=\"elementor-repeater-item-e9022b0 swiper-slide\" role=\"group\" aria-roledescription=\"slide\"><div class=\"swiper-slide-bg\" role=\"img\" aria-label=\"dee-dee-bee-1002\"><\/div><div class=\"swiper-slide-inner\" ><div class=\"swiper-slide-contents\"><\/div><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\" aria-label=\"Previous slide\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-chevron-left\" viewBox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M646 125C629 125 613 133 604 142L308 442C296 454 292 471 292 487 292 504 296 521 308 533L604 854C617 867 629 875 646 875 663 875 679 871 692 858 704 846 713 829 713 812 713 796 708 779 692 767L438 487 692 225C700 217 708 204 708 187 708 171 704 154 692 142 675 129 663 125 646 125Z\"><\/path><\/svg>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\" aria-label=\"Next slide\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-chevron-right\" viewBox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M696 533C708 521 713 504 713 487 713 471 708 454 696 446L400 146C388 133 375 125 354 125 338 125 325 129 313 142 300 154 292 171 292 187 292 204 296 221 308 233L563 492 304 771C292 783 288 800 288 817 288 833 296 850 308 863 321 871 338 875 354 875 371 875 388 867 400 854L696 533Z\"><\/path><\/svg>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-pagination\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-e0b6c76 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e0b6c76\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-5f0bec8\" data-id=\"5f0bec8\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-45c0adc elementor-list-item-link-inline elementor-icon-list--layout-traditional elementor-widget elementor-widget-icon-list\" data-id=\"45c0adc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" id=\"Capa_1\" x=\"0px\" y=\"0px\" viewBox=\"0 0 512 512\" style=\"enable-background:new 0 0 512 512;\" xml:space=\"preserve\"><g>\t<g>\t\t<g>\t\t\t<g>\t\t\t\t<g>\t\t\t\t\t<ellipse cx=\"294.2\" cy=\"103.1\" rx=\"10\" ry=\"12.9\"><\/ellipse>\t\t\t\t<\/g>\t\t\t<\/g>\t\t<\/g>\t<\/g>\t<g>\t\t<path d=\"M16.3,138.1c-2.1,3.6-0.8,8.2,2.8,10.2c1.2,0.7,2.4,1,3.7,1c2.6,0,5.1-1.4,6.5-3.8l43.1-75.8   c14.9-26.1,40.1-45.2,69.3-52.5c13.5-3.3,27.7-3.1,41.1,0.7l34.8,9.8c4,1.1,8.1-1.2,9.3-5.2c1.1-4-1.2-8.1-5.2-9.3l-34.8-9.8   c-15.9-4.5-32.7-4.8-48.8-0.8C105,11,76.3,32.7,59.4,62.4L16.3,138.1L16.3,138.1z\"><\/path>\t\t<path d=\"M493.4,175.4c4-7.6,4.4-16.5,1.1-24.5c-3.3-7.9-9.9-13.9-18.1-16.4L336.5,90.2l-0.9-2.4c-11-29.5-35.7-52.3-66-60.9   l-18.2-5.2c-4-1.1-8.1,1.2-9.3,5.2s1.2,8.1,5.2,9.3l18.2,5.2c25.8,7.3,46.7,26.6,56,51.7l2.2,5.8c0.8,2.2,2.5,3.8,4.7,4.5   l91.9,29.5c-6.2,35.2,4.5,57,14.9,69.2c7,8.2,14.7,13.2,20.1,16l-6.7,19.6c-8.3,24.1-31,40.3-56.4,40.3h-57.5   c-4.1,0-7.5,3.4-7.5,7.5s3.4,7.5,7.5,7.5h57.5c31.9,0,60.3-20.3,70.6-50.4l8.5-24.7L493.4,175.4z M461.3,204.3   c-11-5.9-33.3-23.6-26.5-66.9l37.2,11.4c3.9,1.2,7.1,4.1,8.7,7.9c1.6,3.8,1.4,8.1-0.5,11.7L461.3,204.3L461.3,204.3z\"><\/path>\t\t<path d=\"M59.7,362.9c-4.1,0.2-7.3,3.7-7.1,7.9c2.2,44.1,9.6,54.7,23.7,70.9c5.5,6.4,11.7,13.6,19.1,25.6   c16.2,26.4,46.9,44.7,72.7,44.7c3.6,0,7.1-0.4,10.5-1.1c10.9-2.4,29.8-11.1,33.3-42.3c2.9-25.6,11.6-37.8,20.7-50.7   c11.2-15.8,22.8-32.1,23.5-70.4c0.3-16-3.3-31.6-8.9-47c10.7-5,22.7-7.6,34.7-7.6h23.8c4.1,0,7.5-3.4,7.5-7.5s-3.4-7.5-7.5-7.5   H282c-14,0-27.8,3-40.3,8.6c-4.6-10.7-9.9-21.2-15.1-31.7c-16.8-33.8-32.8-65.7-20-92c12.6-26.1,15.7-51.3,15.3-71l12-26   c1.7-3.8,0.1-8.2-3.7-10c-3.8-1.7-8.2-0.1-10,3.7l-1.6,3.5c-1.2-5.9-2.4-9.5-2.6-10c-1.3-3.9-5.6-6-9.5-4.7   c-3.9,1.3-6,5.6-4.7,9.5c0.2,0.5,15.5,48.3-8.8,98.4c-16,33,1.6,68.1,20.1,105.3c14,28.1,28.5,57.2,28,85.6   c-0.7,33.7-10.4,47.5-20.8,62c-9.8,13.9-20,28.2-23.4,57.7c-1.9,16.7-9.2,26.6-21.7,29.4c-21.3,4.7-52.1-12.1-67.2-36.8   c-8-13-14.9-21.1-20.5-27.5c-12-13.9-18-20.9-20.1-61.9C67.4,365.9,63.8,362.7,59.7,362.9L59.7,362.9z\"><\/path>\t\t<path d=\"M70.5,199.3c4.8,37-0.7,55.3-7,76.6c-4.8,16.3-10.3,34.8-11.4,63.4c-0.2,4.1,3.1,7.6,7.2,7.8c0.1,0,0.2,0,0.3,0   c4,0,7.3-3.2,7.5-7.2c1-26.7,5.9-43.5,10.7-59.7c6.5-22,12.7-42.7,7.5-82.8C78.7,146.1,89.3,96,112.2,69.9   c11.5-13,25.6-19.7,41.9-19.7c4.1,0,7.5-3.4,7.5-7.5s-3.4-7.5-7.5-7.5c-20.5,0-38.9,8.6-53.1,24.8   C75.3,89.2,63.3,143.9,70.5,199.3L70.5,199.3z\"><\/path>\t\t<path d=\"M124,116.1c-1.2,1.9-28.8,46.7-8.3,115.4c9.4,31.7,3.1,55.4-3.6,80.4c-6.6,24.4-13.3,49.7-3.5,81.2c1,3.2,4,5.3,7.2,5.3   c0.7,0,1.5-0.1,2.2-0.3c4-1.2,6.2-5.4,4.9-9.4c-8.5-27.3-2.6-49.4,3.7-72.8c7-26,14.2-52.8,3.5-88.6   c-18.4-61.9,6.4-102.7,6.6-103.1c2.2-3.5,1.1-8.1-2.4-10.3C130.8,111.6,126.2,112.6,124,116.1L124,116.1z\"><\/path>\t\t<path d=\"M160.9,470.9c3.3-0.7,5.7-3.5,5.8-6.9c0.5-9.6,4.9-31.6,29.5-64.6c16.3-22,22.5-48.2,17.9-75.7   c-3.4-20.6-11.7-34.7-12.1-35.3c-2.1-3.6-6.7-4.7-10.3-2.6c-3.6,2.1-4.7,6.7-2.6,10.3c0.2,0.3,7.4,12.8,10.3,30.7   c3.8,23.6-1.3,45-15.3,63.7c-26.4,35.5-31.8,60.1-32.5,72.7C151.5,468.2,156,472,160.9,470.9L160.9,470.9z\"><\/path>\t\t<path d=\"M159.6,300.4c-4.1-0.2-7.7,2.9-7.9,7c0,0.3-1.7,27.7-5,46.1c-0.7,4.1,2,8,6.1,8.7c0.4,0.1,0.9,0.1,1.3,0.1   c3.6,0,6.7-2.6,7.4-6.2c3.4-19.2,5.1-46.6,5.2-47.8C166.9,304.2,163.8,300.7,159.6,300.4L159.6,300.4z\"><\/path>\t\t<path d=\"M170.5,81.7c0.1,0.6,5.6,45.5-25.3,76.4c-2.9,2.9-2.9,7.7,0,10.6c1.5,1.5,3.4,2.2,5.3,2.2c1.9,0,3.8-0.7,5.3-2.2   c36.4-36.4,29.9-86.9,29.6-89.1c-0.6-4.1-4.3-7-8.5-6.4C172.8,73.8,170,77.6,170.5,81.7z\"><\/path>\t<\/g><\/g><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Born: 27\/04\/2022<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-253aac3 elementor-list-item-link-inline elementor-icon-list--layout-traditional elementor-widget elementor-widget-icon-list\" data-id=\"253aac3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" id=\"Capa_1\" x=\"0px\" y=\"0px\" viewBox=\"0 0 512 512\" style=\"enable-background:new 0 0 512 512;\" xml:space=\"preserve\"><g>\t<g>\t\t<path d=\"M376.264,290.173c66.314-66.293,66.314-174.16,0-240.453c-66.314-66.294-174.214-66.294-240.529,0   c-66.314,66.293-66.314,174.16,0,240.453c28.07,28.061,63.591,44.24,100.254,48.546v56.923h-40.018   c-11.051,0-20.009,8.956-20.009,20.003s8.958,20.003,20.009,20.003h40.018v56.348c0.001,11.047,8.959,20.003,20.011,20.003   c11.051,0,20.009-8.956,20.009-20.003v-56.348h40.019c11.051,0,20.009-8.956,20.009-20.003s-8.958-20.003-20.009-20.003h-40.019   V338.72C312.673,334.413,348.194,318.234,376.264,290.173z M164.033,261.884c-50.711-50.695-50.711-133.181,0-183.876   c50.71-50.693,133.221-50.696,183.934,0c50.711,50.695,50.711,133.181,0,183.876C297.256,312.578,214.744,312.578,164.033,261.884   z\"><\/path>\t<\/g><\/g><g><\/g><g><\/g><g><\/g><g><\/g><g><\/g><g><\/g><g><\/g><g><\/g><g><\/g><g><\/g><g><\/g><g><\/g><g><\/g><g><\/g><g><\/g><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Becky Bee Nima<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c8e7b8a elementor-list-item-link-inline elementor-icon-list--layout-traditional elementor-widget elementor-widget-icon-list\" data-id=\"c8e7b8a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" height=\"512\" viewBox=\"0 0 64 64\" width=\"512\"><g id=\"_14._Men_sign\" data-name=\"14. Men sign\"><path d=\"m61 5v20.76a2 2 0 0 1 -2 2h-2.62a2 2 0 0 1 -2-2v-11.14c-.02.02-14.42 14.42-14.45 14.44 9.647 13.666-.652 32.711-17.59 31.92a20.323 20.323 0 0 1 -19.32-21.27c.74-15.817 18.86-24.861 31.93-15.66l14.43-14.43h-11.14a2 2 0 0 1 -2-2v-2.62a2 2 0 0 1 2-2h20.76a2 2 0 0 1 2 2zm-24.81 35.69a12.875 12.875 0 1 0 -12.88 12.87 12.884 12.884 0 0 0 12.88-12.87z\" fill=\"#a5ccf2\"><\/path><\/g><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Starman of the Trav\u2019Lin Star<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-7fc5568\" data-id=\"7fc5568\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-65f37ad elementor-align-center elementor-mobile-align-left elementor-widget elementor-widget-button\" data-id=\"65f37ad\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.setterirlandese.net\/wp-content\/uploads\/2024\/03\/pedigree-dee-dee-bee.pdf\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">PEDIGREE<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-a7f1b56 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"a7f1b56\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-008f1f0\" data-id=\"008f1f0\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a51f890 elementor-widget elementor-widget-heading\" data-id=\"a51f890\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Daycy Dea Delice<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c3bff16 elementor--h-position-center elementor--v-position-middle elementor-arrows-position-inside elementor-pagination-position-inside elementor-widget elementor-widget-slides\" data-id=\"c3bff16\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;autoplay_speed&quot;:3000,&quot;navigation&quot;:&quot;both&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;infinite&quot;:&quot;yes&quot;,&quot;transition&quot;:&quot;slide&quot;,&quot;transition_speed&quot;:500}\" data-widget_type=\"slides.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper\">\n\t\t\t\t\t<div class=\"elementor-slides-wrapper elementor-main-swiper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Slides\" dir=\"ltr\" data-animation=\"fadeInUp\">\n\t\t\t\t<div class=\"swiper-wrapper elementor-slides\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-repeater-item-fce16ce swiper-slide\" role=\"group\" aria-roledescription=\"slide\"><div class=\"swiper-slide-bg\" role=\"img\" aria-label=\"deadelice1001.jpg\"><\/div><div class=\"swiper-slide-inner\" ><div class=\"swiper-slide-contents\"><\/div><\/div><\/div><div class=\"elementor-repeater-item-923c85e swiper-slide\" role=\"group\" aria-roledescription=\"slide\"><div class=\"swiper-slide-bg\" role=\"img\" aria-label=\"deadelice1002.jpg\"><\/div><div class=\"swiper-slide-inner\" ><div class=\"swiper-slide-contents\"><\/div><\/div><\/div><div class=\"elementor-repeater-item-eef5c00 swiper-slide\" role=\"group\" aria-roledescription=\"slide\"><div class=\"swiper-slide-bg\" role=\"img\" aria-label=\"deadelice1003.jpg\"><\/div><div class=\"swiper-slide-inner\" ><div class=\"swiper-slide-contents\"><\/div><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\" aria-label=\"Previous slide\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-chevron-left\" viewBox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M646 125C629 125 613 133 604 142L308 442C296 454 292 471 292 487 292 504 296 521 308 533L604 854C617 867 629 875 646 875 663 875 679 871 692 858 704 846 713 829 713 812 713 796 708 779 692 767L438 487 692 225C700 217 708 204 708 187 708 171 704 154 692 142 675 129 663 125 646 125Z\"><\/path><\/svg>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\" aria-label=\"Next slide\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-chevron-right\" viewBox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M696 533C708 521 713 504 713 487 713 471 708 454 696 446L400 146C388 133 375 125 354 125 338 125 325 129 313 142 300 154 292 171 292 187 292 204 296 221 308 233L563 492 304 771C292 783 288 800 288 817 288 833 296 850 308 863 321 871 338 875 354 875 371 875 388 867 400 854L696 533Z\"><\/path><\/svg>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-pagination\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-fba058d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"fba058d\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-fa2714b\" data-id=\"fa2714b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8b01774 elementor-list-item-link-inline elementor-icon-list--layout-traditional elementor-widget elementor-widget-icon-list\" data-id=\"8b01774\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" id=\"Capa_1\" x=\"0px\" y=\"0px\" viewBox=\"0 0 512 512\" style=\"enable-background:new 0 0 512 512;\" xml:space=\"preserve\"><g>\t<g>\t\t<g>\t\t\t<g>\t\t\t\t<g>\t\t\t\t\t<ellipse cx=\"294.2\" cy=\"103.1\" rx=\"10\" ry=\"12.9\"><\/ellipse>\t\t\t\t<\/g>\t\t\t<\/g>\t\t<\/g>\t<\/g>\t<g>\t\t<path d=\"M16.3,138.1c-2.1,3.6-0.8,8.2,2.8,10.2c1.2,0.7,2.4,1,3.7,1c2.6,0,5.1-1.4,6.5-3.8l43.1-75.8   c14.9-26.1,40.1-45.2,69.3-52.5c13.5-3.3,27.7-3.1,41.1,0.7l34.8,9.8c4,1.1,8.1-1.2,9.3-5.2c1.1-4-1.2-8.1-5.2-9.3l-34.8-9.8   c-15.9-4.5-32.7-4.8-48.8-0.8C105,11,76.3,32.7,59.4,62.4L16.3,138.1L16.3,138.1z\"><\/path>\t\t<path d=\"M493.4,175.4c4-7.6,4.4-16.5,1.1-24.5c-3.3-7.9-9.9-13.9-18.1-16.4L336.5,90.2l-0.9-2.4c-11-29.5-35.7-52.3-66-60.9   l-18.2-5.2c-4-1.1-8.1,1.2-9.3,5.2s1.2,8.1,5.2,9.3l18.2,5.2c25.8,7.3,46.7,26.6,56,51.7l2.2,5.8c0.8,2.2,2.5,3.8,4.7,4.5   l91.9,29.5c-6.2,35.2,4.5,57,14.9,69.2c7,8.2,14.7,13.2,20.1,16l-6.7,19.6c-8.3,24.1-31,40.3-56.4,40.3h-57.5   c-4.1,0-7.5,3.4-7.5,7.5s3.4,7.5,7.5,7.5h57.5c31.9,0,60.3-20.3,70.6-50.4l8.5-24.7L493.4,175.4z M461.3,204.3   c-11-5.9-33.3-23.6-26.5-66.9l37.2,11.4c3.9,1.2,7.1,4.1,8.7,7.9c1.6,3.8,1.4,8.1-0.5,11.7L461.3,204.3L461.3,204.3z\"><\/path>\t\t<path d=\"M59.7,362.9c-4.1,0.2-7.3,3.7-7.1,7.9c2.2,44.1,9.6,54.7,23.7,70.9c5.5,6.4,11.7,13.6,19.1,25.6   c16.2,26.4,46.9,44.7,72.7,44.7c3.6,0,7.1-0.4,10.5-1.1c10.9-2.4,29.8-11.1,33.3-42.3c2.9-25.6,11.6-37.8,20.7-50.7   c11.2-15.8,22.8-32.1,23.5-70.4c0.3-16-3.3-31.6-8.9-47c10.7-5,22.7-7.6,34.7-7.6h23.8c4.1,0,7.5-3.4,7.5-7.5s-3.4-7.5-7.5-7.5   H282c-14,0-27.8,3-40.3,8.6c-4.6-10.7-9.9-21.2-15.1-31.7c-16.8-33.8-32.8-65.7-20-92c12.6-26.1,15.7-51.3,15.3-71l12-26   c1.7-3.8,0.1-8.2-3.7-10c-3.8-1.7-8.2-0.1-10,3.7l-1.6,3.5c-1.2-5.9-2.4-9.5-2.6-10c-1.3-3.9-5.6-6-9.5-4.7   c-3.9,1.3-6,5.6-4.7,9.5c0.2,0.5,15.5,48.3-8.8,98.4c-16,33,1.6,68.1,20.1,105.3c14,28.1,28.5,57.2,28,85.6   c-0.7,33.7-10.4,47.5-20.8,62c-9.8,13.9-20,28.2-23.4,57.7c-1.9,16.7-9.2,26.6-21.7,29.4c-21.3,4.7-52.1-12.1-67.2-36.8   c-8-13-14.9-21.1-20.5-27.5c-12-13.9-18-20.9-20.1-61.9C67.4,365.9,63.8,362.7,59.7,362.9L59.7,362.9z\"><\/path>\t\t<path d=\"M70.5,199.3c4.8,37-0.7,55.3-7,76.6c-4.8,16.3-10.3,34.8-11.4,63.4c-0.2,4.1,3.1,7.6,7.2,7.8c0.1,0,0.2,0,0.3,0   c4,0,7.3-3.2,7.5-7.2c1-26.7,5.9-43.5,10.7-59.7c6.5-22,12.7-42.7,7.5-82.8C78.7,146.1,89.3,96,112.2,69.9   c11.5-13,25.6-19.7,41.9-19.7c4.1,0,7.5-3.4,7.5-7.5s-3.4-7.5-7.5-7.5c-20.5,0-38.9,8.6-53.1,24.8   C75.3,89.2,63.3,143.9,70.5,199.3L70.5,199.3z\"><\/path>\t\t<path d=\"M124,116.1c-1.2,1.9-28.8,46.7-8.3,115.4c9.4,31.7,3.1,55.4-3.6,80.4c-6.6,24.4-13.3,49.7-3.5,81.2c1,3.2,4,5.3,7.2,5.3   c0.7,0,1.5-0.1,2.2-0.3c4-1.2,6.2-5.4,4.9-9.4c-8.5-27.3-2.6-49.4,3.7-72.8c7-26,14.2-52.8,3.5-88.6   c-18.4-61.9,6.4-102.7,6.6-103.1c2.2-3.5,1.1-8.1-2.4-10.3C130.8,111.6,126.2,112.6,124,116.1L124,116.1z\"><\/path>\t\t<path d=\"M160.9,470.9c3.3-0.7,5.7-3.5,5.8-6.9c0.5-9.6,4.9-31.6,29.5-64.6c16.3-22,22.5-48.2,17.9-75.7   c-3.4-20.6-11.7-34.7-12.1-35.3c-2.1-3.6-6.7-4.7-10.3-2.6c-3.6,2.1-4.7,6.7-2.6,10.3c0.2,0.3,7.4,12.8,10.3,30.7   c3.8,23.6-1.3,45-15.3,63.7c-26.4,35.5-31.8,60.1-32.5,72.7C151.5,468.2,156,472,160.9,470.9L160.9,470.9z\"><\/path>\t\t<path d=\"M159.6,300.4c-4.1-0.2-7.7,2.9-7.9,7c0,0.3-1.7,27.7-5,46.1c-0.7,4.1,2,8,6.1,8.7c0.4,0.1,0.9,0.1,1.3,0.1   c3.6,0,6.7-2.6,7.4-6.2c3.4-19.2,5.1-46.6,5.2-47.8C166.9,304.2,163.8,300.7,159.6,300.4L159.6,300.4z\"><\/path>\t\t<path d=\"M170.5,81.7c0.1,0.6,5.6,45.5-25.3,76.4c-2.9,2.9-2.9,7.7,0,10.6c1.5,1.5,3.4,2.2,5.3,2.2c1.9,0,3.8-0.7,5.3-2.2   c36.4-36.4,29.9-86.9,29.6-89.1c-0.6-4.1-4.3-7-8.5-6.4C172.8,73.8,170,77.6,170.5,81.7z\"><\/path>\t<\/g><\/g><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Born: 27\/04\/2022<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1c0aa41 elementor-list-item-link-inline elementor-icon-list--layout-traditional elementor-widget elementor-widget-icon-list\" data-id=\"1c0aa41\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" id=\"Capa_1\" x=\"0px\" y=\"0px\" viewBox=\"0 0 512 512\" style=\"enable-background:new 0 0 512 512;\" xml:space=\"preserve\"><g>\t<g>\t\t<path d=\"M376.264,290.173c66.314-66.293,66.314-174.16,0-240.453c-66.314-66.294-174.214-66.294-240.529,0   c-66.314,66.293-66.314,174.16,0,240.453c28.07,28.061,63.591,44.24,100.254,48.546v56.923h-40.018   c-11.051,0-20.009,8.956-20.009,20.003s8.958,20.003,20.009,20.003h40.018v56.348c0.001,11.047,8.959,20.003,20.011,20.003   c11.051,0,20.009-8.956,20.009-20.003v-56.348h40.019c11.051,0,20.009-8.956,20.009-20.003s-8.958-20.003-20.009-20.003h-40.019   V338.72C312.673,334.413,348.194,318.234,376.264,290.173z M164.033,261.884c-50.711-50.695-50.711-133.181,0-183.876   c50.71-50.693,133.221-50.696,183.934,0c50.711,50.695,50.711,133.181,0,183.876C297.256,312.578,214.744,312.578,164.033,261.884   z\"><\/path>\t<\/g><\/g><g><\/g><g><\/g><g><\/g><g><\/g><g><\/g><g><\/g><g><\/g><g><\/g><g><\/g><g><\/g><g><\/g><g><\/g><g><\/g><g><\/g><g><\/g><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Becky Bee Nima<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b1d98ae elementor-list-item-link-inline elementor-icon-list--layout-traditional elementor-widget elementor-widget-icon-list\" data-id=\"b1d98ae\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" height=\"512\" viewBox=\"0 0 64 64\" width=\"512\"><g id=\"_14._Men_sign\" data-name=\"14. Men sign\"><path d=\"m61 5v20.76a2 2 0 0 1 -2 2h-2.62a2 2 0 0 1 -2-2v-11.14c-.02.02-14.42 14.42-14.45 14.44 9.647 13.666-.652 32.711-17.59 31.92a20.323 20.323 0 0 1 -19.32-21.27c.74-15.817 18.86-24.861 31.93-15.66l14.43-14.43h-11.14a2 2 0 0 1 -2-2v-2.62a2 2 0 0 1 2-2h20.76a2 2 0 0 1 2 2zm-24.81 35.69a12.875 12.875 0 1 0 -12.88 12.87 12.884 12.884 0 0 0 12.88-12.87z\" fill=\"#a5ccf2\"><\/path><\/g><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Starman of the Trav\u2019Lin Star<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-a97514a\" data-id=\"a97514a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-48c42e4 elementor-align-center elementor-mobile-align-left elementor-widget elementor-widget-button\" data-id=\"48c42e4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.setterirlandese.net\/wp-content\/uploads\/2024\/03\/pedigree-daycy-dea-felice.pdf\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">PEDIGREE<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-8b2e1ca\" data-id=\"8b2e1ca\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-036412c elementor-widget elementor-widget-heading\" data-id=\"036412c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Global Foundries<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-25f3e41 elementor--h-position-center elementor--v-position-middle elementor-arrows-position-inside elementor-pagination-position-inside elementor-widget elementor-widget-slides\" data-id=\"25f3e41\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;autoplay_speed&quot;:3000,&quot;navigation&quot;:&quot;both&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;infinite&quot;:&quot;yes&quot;,&quot;transition&quot;:&quot;slide&quot;,&quot;transition_speed&quot;:500}\" data-widget_type=\"slides.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper\">\n\t\t\t\t\t<div class=\"elementor-slides-wrapper elementor-main-swiper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Slides\" dir=\"ltr\" data-animation=\"fadeInUp\">\n\t\t\t\t<div class=\"swiper-wrapper elementor-slides\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-repeater-item-fce16ce swiper-slide\" role=\"group\" aria-roledescription=\"slide\"><div class=\"swiper-slide-bg\" role=\"img\" aria-label=\"global-foundries001\"><\/div><div class=\"swiper-slide-inner\" ><div class=\"swiper-slide-contents\"><\/div><\/div><\/div><div class=\"elementor-repeater-item-70257df swiper-slide\" role=\"group\" aria-roledescription=\"slide\"><div class=\"swiper-slide-bg\" role=\"img\" aria-label=\"global-foundries002\"><\/div><div class=\"swiper-slide-inner\" ><div class=\"swiper-slide-contents\"><\/div><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\" aria-label=\"Previous slide\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-chevron-left\" viewBox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M646 125C629 125 613 133 604 142L308 442C296 454 292 471 292 487 292 504 296 521 308 533L604 854C617 867 629 875 646 875 663 875 679 871 692 858 704 846 713 829 713 812 713 796 708 779 692 767L438 487 692 225C700 217 708 204 708 187 708 171 704 154 692 142 675 129 663 125 646 125Z\"><\/path><\/svg>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\" aria-label=\"Next slide\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-chevron-right\" viewBox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M696 533C708 521 713 504 713 487 713 471 708 454 696 446L400 146C388 133 375 125 354 125 338 125 325 129 313 142 300 154 292 171 292 187 292 204 296 221 308 233L563 492 304 771C292 783 288 800 288 817 288 833 296 850 308 863 321 871 338 875 354 875 371 875 388 867 400 854L696 533Z\"><\/path><\/svg>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-pagination\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-ab7997e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"ab7997e\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-9368ef6\" data-id=\"9368ef6\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-fe128dd elementor-list-item-link-inline elementor-icon-list--layout-traditional elementor-widget elementor-widget-icon-list\" data-id=\"fe128dd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" id=\"Capa_1\" x=\"0px\" y=\"0px\" viewBox=\"0 0 512 512\" style=\"enable-background:new 0 0 512 512;\" xml:space=\"preserve\"><g>\t<g>\t\t<g>\t\t\t<g>\t\t\t\t<g>\t\t\t\t\t<ellipse cx=\"294.2\" cy=\"103.1\" rx=\"10\" ry=\"12.9\"><\/ellipse>\t\t\t\t<\/g>\t\t\t<\/g>\t\t<\/g>\t<\/g>\t<g>\t\t<path d=\"M16.3,138.1c-2.1,3.6-0.8,8.2,2.8,10.2c1.2,0.7,2.4,1,3.7,1c2.6,0,5.1-1.4,6.5-3.8l43.1-75.8   c14.9-26.1,40.1-45.2,69.3-52.5c13.5-3.3,27.7-3.1,41.1,0.7l34.8,9.8c4,1.1,8.1-1.2,9.3-5.2c1.1-4-1.2-8.1-5.2-9.3l-34.8-9.8   c-15.9-4.5-32.7-4.8-48.8-0.8C105,11,76.3,32.7,59.4,62.4L16.3,138.1L16.3,138.1z\"><\/path>\t\t<path d=\"M493.4,175.4c4-7.6,4.4-16.5,1.1-24.5c-3.3-7.9-9.9-13.9-18.1-16.4L336.5,90.2l-0.9-2.4c-11-29.5-35.7-52.3-66-60.9   l-18.2-5.2c-4-1.1-8.1,1.2-9.3,5.2s1.2,8.1,5.2,9.3l18.2,5.2c25.8,7.3,46.7,26.6,56,51.7l2.2,5.8c0.8,2.2,2.5,3.8,4.7,4.5   l91.9,29.5c-6.2,35.2,4.5,57,14.9,69.2c7,8.2,14.7,13.2,20.1,16l-6.7,19.6c-8.3,24.1-31,40.3-56.4,40.3h-57.5   c-4.1,0-7.5,3.4-7.5,7.5s3.4,7.5,7.5,7.5h57.5c31.9,0,60.3-20.3,70.6-50.4l8.5-24.7L493.4,175.4z M461.3,204.3   c-11-5.9-33.3-23.6-26.5-66.9l37.2,11.4c3.9,1.2,7.1,4.1,8.7,7.9c1.6,3.8,1.4,8.1-0.5,11.7L461.3,204.3L461.3,204.3z\"><\/path>\t\t<path d=\"M59.7,362.9c-4.1,0.2-7.3,3.7-7.1,7.9c2.2,44.1,9.6,54.7,23.7,70.9c5.5,6.4,11.7,13.6,19.1,25.6   c16.2,26.4,46.9,44.7,72.7,44.7c3.6,0,7.1-0.4,10.5-1.1c10.9-2.4,29.8-11.1,33.3-42.3c2.9-25.6,11.6-37.8,20.7-50.7   c11.2-15.8,22.8-32.1,23.5-70.4c0.3-16-3.3-31.6-8.9-47c10.7-5,22.7-7.6,34.7-7.6h23.8c4.1,0,7.5-3.4,7.5-7.5s-3.4-7.5-7.5-7.5   H282c-14,0-27.8,3-40.3,8.6c-4.6-10.7-9.9-21.2-15.1-31.7c-16.8-33.8-32.8-65.7-20-92c12.6-26.1,15.7-51.3,15.3-71l12-26   c1.7-3.8,0.1-8.2-3.7-10c-3.8-1.7-8.2-0.1-10,3.7l-1.6,3.5c-1.2-5.9-2.4-9.5-2.6-10c-1.3-3.9-5.6-6-9.5-4.7   c-3.9,1.3-6,5.6-4.7,9.5c0.2,0.5,15.5,48.3-8.8,98.4c-16,33,1.6,68.1,20.1,105.3c14,28.1,28.5,57.2,28,85.6   c-0.7,33.7-10.4,47.5-20.8,62c-9.8,13.9-20,28.2-23.4,57.7c-1.9,16.7-9.2,26.6-21.7,29.4c-21.3,4.7-52.1-12.1-67.2-36.8   c-8-13-14.9-21.1-20.5-27.5c-12-13.9-18-20.9-20.1-61.9C67.4,365.9,63.8,362.7,59.7,362.9L59.7,362.9z\"><\/path>\t\t<path d=\"M70.5,199.3c4.8,37-0.7,55.3-7,76.6c-4.8,16.3-10.3,34.8-11.4,63.4c-0.2,4.1,3.1,7.6,7.2,7.8c0.1,0,0.2,0,0.3,0   c4,0,7.3-3.2,7.5-7.2c1-26.7,5.9-43.5,10.7-59.7c6.5-22,12.7-42.7,7.5-82.8C78.7,146.1,89.3,96,112.2,69.9   c11.5-13,25.6-19.7,41.9-19.7c4.1,0,7.5-3.4,7.5-7.5s-3.4-7.5-7.5-7.5c-20.5,0-38.9,8.6-53.1,24.8   C75.3,89.2,63.3,143.9,70.5,199.3L70.5,199.3z\"><\/path>\t\t<path d=\"M124,116.1c-1.2,1.9-28.8,46.7-8.3,115.4c9.4,31.7,3.1,55.4-3.6,80.4c-6.6,24.4-13.3,49.7-3.5,81.2c1,3.2,4,5.3,7.2,5.3   c0.7,0,1.5-0.1,2.2-0.3c4-1.2,6.2-5.4,4.9-9.4c-8.5-27.3-2.6-49.4,3.7-72.8c7-26,14.2-52.8,3.5-88.6   c-18.4-61.9,6.4-102.7,6.6-103.1c2.2-3.5,1.1-8.1-2.4-10.3C130.8,111.6,126.2,112.6,124,116.1L124,116.1z\"><\/path>\t\t<path d=\"M160.9,470.9c3.3-0.7,5.7-3.5,5.8-6.9c0.5-9.6,4.9-31.6,29.5-64.6c16.3-22,22.5-48.2,17.9-75.7   c-3.4-20.6-11.7-34.7-12.1-35.3c-2.1-3.6-6.7-4.7-10.3-2.6c-3.6,2.1-4.7,6.7-2.6,10.3c0.2,0.3,7.4,12.8,10.3,30.7   c3.8,23.6-1.3,45-15.3,63.7c-26.4,35.5-31.8,60.1-32.5,72.7C151.5,468.2,156,472,160.9,470.9L160.9,470.9z\"><\/path>\t\t<path d=\"M159.6,300.4c-4.1-0.2-7.7,2.9-7.9,7c0,0.3-1.7,27.7-5,46.1c-0.7,4.1,2,8,6.1,8.7c0.4,0.1,0.9,0.1,1.3,0.1   c3.6,0,6.7-2.6,7.4-6.2c3.4-19.2,5.1-46.6,5.2-47.8C166.9,304.2,163.8,300.7,159.6,300.4L159.6,300.4z\"><\/path>\t\t<path d=\"M170.5,81.7c0.1,0.6,5.6,45.5-25.3,76.4c-2.9,2.9-2.9,7.7,0,10.6c1.5,1.5,3.4,2.2,5.3,2.2c1.9,0,3.8-0.7,5.3-2.2   c36.4-36.4,29.9-86.9,29.6-89.1c-0.6-4.1-4.3-7-8.5-6.4C172.8,73.8,170,77.6,170.5,81.7z\"><\/path>\t<\/g><\/g><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Born: 16\/08\/2025<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ad6bb67 elementor-list-item-link-inline elementor-icon-list--layout-traditional elementor-widget elementor-widget-icon-list\" data-id=\"ad6bb67\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" id=\"Capa_1\" x=\"0px\" y=\"0px\" viewBox=\"0 0 512 512\" style=\"enable-background:new 0 0 512 512;\" xml:space=\"preserve\"><g>\t<g>\t\t<path d=\"M376.264,290.173c66.314-66.293,66.314-174.16,0-240.453c-66.314-66.294-174.214-66.294-240.529,0   c-66.314,66.293-66.314,174.16,0,240.453c28.07,28.061,63.591,44.24,100.254,48.546v56.923h-40.018   c-11.051,0-20.009,8.956-20.009,20.003s8.958,20.003,20.009,20.003h40.018v56.348c0.001,11.047,8.959,20.003,20.011,20.003   c11.051,0,20.009-8.956,20.009-20.003v-56.348h40.019c11.051,0,20.009-8.956,20.009-20.003s-8.958-20.003-20.009-20.003h-40.019   V338.72C312.673,334.413,348.194,318.234,376.264,290.173z M164.033,261.884c-50.711-50.695-50.711-133.181,0-183.876   c50.71-50.693,133.221-50.696,183.934,0c50.711,50.695,50.711,133.181,0,183.876C297.256,312.578,214.744,312.578,164.033,261.884   z\"><\/path>\t<\/g><\/g><g><\/g><g><\/g><g><\/g><g><\/g><g><\/g><g><\/g><g><\/g><g><\/g><g><\/g><g><\/g><g><\/g><g><\/g><g><\/g><g><\/g><g><\/g><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Summer Dream<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9a27278 elementor-list-item-link-inline elementor-icon-list--layout-traditional elementor-widget elementor-widget-icon-list\" data-id=\"9a27278\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" height=\"512\" viewBox=\"0 0 64 64\" width=\"512\"><g id=\"_14._Men_sign\" data-name=\"14. Men sign\"><path d=\"m61 5v20.76a2 2 0 0 1 -2 2h-2.62a2 2 0 0 1 -2-2v-11.14c-.02.02-14.42 14.42-14.45 14.44 9.647 13.666-.652 32.711-17.59 31.92a20.323 20.323 0 0 1 -19.32-21.27c.74-15.817 18.86-24.861 31.93-15.66l14.43-14.43h-11.14a2 2 0 0 1 -2-2v-2.62a2 2 0 0 1 2-2h20.76a2 2 0 0 1 2 2zm-24.81 35.69a12.875 12.875 0 1 0 -12.88 12.87 12.884 12.884 0 0 0 12.88-12.87z\" fill=\"#a5ccf2\"><\/path><\/g><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Chase<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-365ccff\" data-id=\"365ccff\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-56fa318 elementor-align-center elementor-mobile-align-left elementor-widget elementor-widget-button\" data-id=\"56fa318\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">PEDIGREE<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-016c134 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"016c134\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-716ce58\" data-id=\"716ce58\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ce44864 elementor-widget elementor-widget-heading\" data-id=\"ce44864\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Hannah<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-180f125 elementor--h-position-center elementor--v-position-middle elementor-arrows-position-inside elementor-pagination-position-inside elementor-widget elementor-widget-slides\" data-id=\"180f125\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;autoplay_speed&quot;:3000,&quot;navigation&quot;:&quot;both&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;infinite&quot;:&quot;yes&quot;,&quot;transition&quot;:&quot;slide&quot;,&quot;transition_speed&quot;:500}\" data-widget_type=\"slides.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper\">\n\t\t\t\t\t<div class=\"elementor-slides-wrapper elementor-main-swiper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Slides\" dir=\"ltr\" data-animation=\"fadeInUp\">\n\t\t\t\t<div class=\"swiper-wrapper elementor-slides\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-repeater-item-fce16ce swiper-slide\" role=\"group\" aria-roledescription=\"slide\"><div class=\"swiper-slide-bg\" role=\"img\" aria-label=\"hannah\"><\/div><div class=\"swiper-slide-inner\" ><div class=\"swiper-slide-contents\"><\/div><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-6960a02 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6960a02\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-365eb7c\" data-id=\"365eb7c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-bcb5363 elementor-list-item-link-inline elementor-icon-list--layout-traditional elementor-widget elementor-widget-icon-list\" data-id=\"bcb5363\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" id=\"Capa_1\" x=\"0px\" y=\"0px\" viewBox=\"0 0 512 512\" style=\"enable-background:new 0 0 512 512;\" xml:space=\"preserve\"><g>\t<g>\t\t<g>\t\t\t<g>\t\t\t\t<g>\t\t\t\t\t<ellipse cx=\"294.2\" cy=\"103.1\" rx=\"10\" ry=\"12.9\"><\/ellipse>\t\t\t\t<\/g>\t\t\t<\/g>\t\t<\/g>\t<\/g>\t<g>\t\t<path d=\"M16.3,138.1c-2.1,3.6-0.8,8.2,2.8,10.2c1.2,0.7,2.4,1,3.7,1c2.6,0,5.1-1.4,6.5-3.8l43.1-75.8   c14.9-26.1,40.1-45.2,69.3-52.5c13.5-3.3,27.7-3.1,41.1,0.7l34.8,9.8c4,1.1,8.1-1.2,9.3-5.2c1.1-4-1.2-8.1-5.2-9.3l-34.8-9.8   c-15.9-4.5-32.7-4.8-48.8-0.8C105,11,76.3,32.7,59.4,62.4L16.3,138.1L16.3,138.1z\"><\/path>\t\t<path d=\"M493.4,175.4c4-7.6,4.4-16.5,1.1-24.5c-3.3-7.9-9.9-13.9-18.1-16.4L336.5,90.2l-0.9-2.4c-11-29.5-35.7-52.3-66-60.9   l-18.2-5.2c-4-1.1-8.1,1.2-9.3,5.2s1.2,8.1,5.2,9.3l18.2,5.2c25.8,7.3,46.7,26.6,56,51.7l2.2,5.8c0.8,2.2,2.5,3.8,4.7,4.5   l91.9,29.5c-6.2,35.2,4.5,57,14.9,69.2c7,8.2,14.7,13.2,20.1,16l-6.7,19.6c-8.3,24.1-31,40.3-56.4,40.3h-57.5   c-4.1,0-7.5,3.4-7.5,7.5s3.4,7.5,7.5,7.5h57.5c31.9,0,60.3-20.3,70.6-50.4l8.5-24.7L493.4,175.4z M461.3,204.3   c-11-5.9-33.3-23.6-26.5-66.9l37.2,11.4c3.9,1.2,7.1,4.1,8.7,7.9c1.6,3.8,1.4,8.1-0.5,11.7L461.3,204.3L461.3,204.3z\"><\/path>\t\t<path d=\"M59.7,362.9c-4.1,0.2-7.3,3.7-7.1,7.9c2.2,44.1,9.6,54.7,23.7,70.9c5.5,6.4,11.7,13.6,19.1,25.6   c16.2,26.4,46.9,44.7,72.7,44.7c3.6,0,7.1-0.4,10.5-1.1c10.9-2.4,29.8-11.1,33.3-42.3c2.9-25.6,11.6-37.8,20.7-50.7   c11.2-15.8,22.8-32.1,23.5-70.4c0.3-16-3.3-31.6-8.9-47c10.7-5,22.7-7.6,34.7-7.6h23.8c4.1,0,7.5-3.4,7.5-7.5s-3.4-7.5-7.5-7.5   H282c-14,0-27.8,3-40.3,8.6c-4.6-10.7-9.9-21.2-15.1-31.7c-16.8-33.8-32.8-65.7-20-92c12.6-26.1,15.7-51.3,15.3-71l12-26   c1.7-3.8,0.1-8.2-3.7-10c-3.8-1.7-8.2-0.1-10,3.7l-1.6,3.5c-1.2-5.9-2.4-9.5-2.6-10c-1.3-3.9-5.6-6-9.5-4.7   c-3.9,1.3-6,5.6-4.7,9.5c0.2,0.5,15.5,48.3-8.8,98.4c-16,33,1.6,68.1,20.1,105.3c14,28.1,28.5,57.2,28,85.6   c-0.7,33.7-10.4,47.5-20.8,62c-9.8,13.9-20,28.2-23.4,57.7c-1.9,16.7-9.2,26.6-21.7,29.4c-21.3,4.7-52.1-12.1-67.2-36.8   c-8-13-14.9-21.1-20.5-27.5c-12-13.9-18-20.9-20.1-61.9C67.4,365.9,63.8,362.7,59.7,362.9L59.7,362.9z\"><\/path>\t\t<path d=\"M70.5,199.3c4.8,37-0.7,55.3-7,76.6c-4.8,16.3-10.3,34.8-11.4,63.4c-0.2,4.1,3.1,7.6,7.2,7.8c0.1,0,0.2,0,0.3,0   c4,0,7.3-3.2,7.5-7.2c1-26.7,5.9-43.5,10.7-59.7c6.5-22,12.7-42.7,7.5-82.8C78.7,146.1,89.3,96,112.2,69.9   c11.5-13,25.6-19.7,41.9-19.7c4.1,0,7.5-3.4,7.5-7.5s-3.4-7.5-7.5-7.5c-20.5,0-38.9,8.6-53.1,24.8   C75.3,89.2,63.3,143.9,70.5,199.3L70.5,199.3z\"><\/path>\t\t<path d=\"M124,116.1c-1.2,1.9-28.8,46.7-8.3,115.4c9.4,31.7,3.1,55.4-3.6,80.4c-6.6,24.4-13.3,49.7-3.5,81.2c1,3.2,4,5.3,7.2,5.3   c0.7,0,1.5-0.1,2.2-0.3c4-1.2,6.2-5.4,4.9-9.4c-8.5-27.3-2.6-49.4,3.7-72.8c7-26,14.2-52.8,3.5-88.6   c-18.4-61.9,6.4-102.7,6.6-103.1c2.2-3.5,1.1-8.1-2.4-10.3C130.8,111.6,126.2,112.6,124,116.1L124,116.1z\"><\/path>\t\t<path d=\"M160.9,470.9c3.3-0.7,5.7-3.5,5.8-6.9c0.5-9.6,4.9-31.6,29.5-64.6c16.3-22,22.5-48.2,17.9-75.7   c-3.4-20.6-11.7-34.7-12.1-35.3c-2.1-3.6-6.7-4.7-10.3-2.6c-3.6,2.1-4.7,6.7-2.6,10.3c0.2,0.3,7.4,12.8,10.3,30.7   c3.8,23.6-1.3,45-15.3,63.7c-26.4,35.5-31.8,60.1-32.5,72.7C151.5,468.2,156,472,160.9,470.9L160.9,470.9z\"><\/path>\t\t<path d=\"M159.6,300.4c-4.1-0.2-7.7,2.9-7.9,7c0,0.3-1.7,27.7-5,46.1c-0.7,4.1,2,8,6.1,8.7c0.4,0.1,0.9,0.1,1.3,0.1   c3.6,0,6.7-2.6,7.4-6.2c3.4-19.2,5.1-46.6,5.2-47.8C166.9,304.2,163.8,300.7,159.6,300.4L159.6,300.4z\"><\/path>\t\t<path d=\"M170.5,81.7c0.1,0.6,5.6,45.5-25.3,76.4c-2.9,2.9-2.9,7.7,0,10.6c1.5,1.5,3.4,2.2,5.3,2.2c1.9,0,3.8-0.7,5.3-2.2   c36.4-36.4,29.9-86.9,29.6-89.1c-0.6-4.1-4.3-7-8.5-6.4C172.8,73.8,170,77.6,170.5,81.7z\"><\/path>\t<\/g><\/g><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Born: 01\/10\/2025<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9990642 elementor-list-item-link-inline elementor-icon-list--layout-traditional elementor-widget elementor-widget-icon-list\" data-id=\"9990642\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" id=\"Capa_1\" x=\"0px\" y=\"0px\" viewBox=\"0 0 512 512\" style=\"enable-background:new 0 0 512 512;\" xml:space=\"preserve\"><g>\t<g>\t\t<path d=\"M376.264,290.173c66.314-66.293,66.314-174.16,0-240.453c-66.314-66.294-174.214-66.294-240.529,0   c-66.314,66.293-66.314,174.16,0,240.453c28.07,28.061,63.591,44.24,100.254,48.546v56.923h-40.018   c-11.051,0-20.009,8.956-20.009,20.003s8.958,20.003,20.009,20.003h40.018v56.348c0.001,11.047,8.959,20.003,20.011,20.003   c11.051,0,20.009-8.956,20.009-20.003v-56.348h40.019c11.051,0,20.009-8.956,20.009-20.003s-8.958-20.003-20.009-20.003h-40.019   V338.72C312.673,334.413,348.194,318.234,376.264,290.173z M164.033,261.884c-50.711-50.695-50.711-133.181,0-183.876   c50.71-50.693,133.221-50.696,183.934,0c50.711,50.695,50.711,133.181,0,183.876C297.256,312.578,214.744,312.578,164.033,261.884   z\"><\/path>\t<\/g><\/g><g><\/g><g><\/g><g><\/g><g><\/g><g><\/g><g><\/g><g><\/g><g><\/g><g><\/g><g><\/g><g><\/g><g><\/g><g><\/g><g><\/g><g><\/g><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Daycy Dea Delice<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7a6b298 elementor-list-item-link-inline elementor-icon-list--layout-traditional elementor-widget elementor-widget-icon-list\" data-id=\"7a6b298\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" height=\"512\" viewBox=\"0 0 64 64\" width=\"512\"><g id=\"_14._Men_sign\" data-name=\"14. Men sign\"><path d=\"m61 5v20.76a2 2 0 0 1 -2 2h-2.62a2 2 0 0 1 -2-2v-11.14c-.02.02-14.42 14.42-14.45 14.44 9.647 13.666-.652 32.711-17.59 31.92a20.323 20.323 0 0 1 -19.32-21.27c.74-15.817 18.86-24.861 31.93-15.66l14.43-14.43h-11.14a2 2 0 0 1 -2-2v-2.62a2 2 0 0 1 2-2h20.76a2 2 0 0 1 2 2zm-24.81 35.69a12.875 12.875 0 1 0 -12.88 12.87 12.884 12.884 0 0 0 12.88-12.87z\" fill=\"#a5ccf2\"><\/path><\/g><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Chase<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-c48eb4e\" data-id=\"c48eb4e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-07d32f6 elementor-align-center elementor-mobile-align-left elementor-widget elementor-widget-button\" data-id=\"07d32f6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">PEDIGREE<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-8457991\" data-id=\"8457991\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Irish Setter female Female Irish Setters &#8211; Welcome to the page, below you can find out which females are part of our kennel. Some of them are champions, others young promises and still others excellent bitches but all rigorously healthy and adhering to the standard of the Irish setter both in terms of appearance and [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":2857,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-2603","page","type-page","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.1.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Female Irish Setters - Scarna&#039;s Red Dream Kennel<\/title>\n<meta name=\"description\" content=\"Female Irish Setters - Welcome to the page, below you can find out which females are part of our kennel.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.setterirlandese.net\/en\/irish-setter-female\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Female Irish Setters - Scarna&#039;s Red Dream Kennel\" \/>\n<meta property=\"og:description\" content=\"Female Irish Setters - Welcome to the page, below you can find out which females are part of our kennel.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.setterirlandese.net\/en\/irish-setter-female\/\" \/>\n<meta property=\"og:site_name\" content=\"Setter Irlandese Scarna&#039;s Red Dream\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-05T16:41:41+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.setterirlandese.net\/wp-content\/uploads\/2022\/03\/setter-irlandesi-femmina.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.setterirlandese.net\/en\/irish-setter-female\/\",\"url\":\"https:\/\/www.setterirlandese.net\/en\/irish-setter-female\/\",\"name\":\"Female Irish Setters - Scarna's Red Dream Kennel\",\"isPartOf\":{\"@id\":\"https:\/\/www.setterirlandese.net\/en\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.setterirlandese.net\/en\/irish-setter-female\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.setterirlandese.net\/en\/irish-setter-female\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.setterirlandese.net\/wp-content\/uploads\/2022\/03\/setter-irlandesi-femmina.jpg\",\"datePublished\":\"2022-03-01T15:56:47+00:00\",\"dateModified\":\"2025-12-05T16:41:41+00:00\",\"description\":\"Female Irish Setters - Welcome to the page, below you can find out which females are part of our kennel.\",\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.setterirlandese.net\/en\/irish-setter-female\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.setterirlandese.net\/en\/irish-setter-female\/#primaryimage\",\"url\":\"https:\/\/www.setterirlandese.net\/wp-content\/uploads\/2022\/03\/setter-irlandesi-femmina.jpg\",\"contentUrl\":\"https:\/\/www.setterirlandese.net\/wp-content\/uploads\/2022\/03\/setter-irlandesi-femmina.jpg\",\"width\":600,\"height\":314},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.setterirlandese.net\/en\/#website\",\"url\":\"https:\/\/www.setterirlandese.net\/en\/\",\"name\":\"Setter Irlandese Scarna&#039;s Red Dream\",\"description\":\"Allevamento Setter Irlandesi\",\"publisher\":{\"@id\":\"https:\/\/www.setterirlandese.net\/en\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.setterirlandese.net\/en\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.setterirlandese.net\/en\/#organization\",\"name\":\"Setter Irlandese Scarna&#039;s Red Dream\",\"url\":\"https:\/\/www.setterirlandese.net\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.setterirlandese.net\/en\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.setterirlandese.net\/wp-content\/uploads\/2022\/02\/logo-scarnas-red-dream.png\",\"contentUrl\":\"https:\/\/www.setterirlandese.net\/wp-content\/uploads\/2022\/02\/logo-scarnas-red-dream.png\",\"width\":624,\"height\":624,\"caption\":\"Setter Irlandese Scarna&#039;s Red Dream\"},\"image\":{\"@id\":\"https:\/\/www.setterirlandese.net\/en\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Female Irish Setters - Scarna's Red Dream Kennel","description":"Female Irish Setters - Welcome to the page, below you can find out which females are part of our kennel.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.setterirlandese.net\/en\/irish-setter-female\/","og_locale":"en_US","og_type":"article","og_title":"Female Irish Setters - Scarna's Red Dream Kennel","og_description":"Female Irish Setters - Welcome to the page, below you can find out which females are part of our kennel.","og_url":"https:\/\/www.setterirlandese.net\/en\/irish-setter-female\/","og_site_name":"Setter Irlandese Scarna&#039;s Red Dream","article_modified_time":"2025-12-05T16:41:41+00:00","og_image":[{"url":"https:\/\/www.setterirlandese.net\/wp-content\/uploads\/2022\/03\/setter-irlandesi-femmina.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.setterirlandese.net\/en\/irish-setter-female\/","url":"https:\/\/www.setterirlandese.net\/en\/irish-setter-female\/","name":"Female Irish Setters - Scarna's Red Dream Kennel","isPartOf":{"@id":"https:\/\/www.setterirlandese.net\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.setterirlandese.net\/en\/irish-setter-female\/#primaryimage"},"image":{"@id":"https:\/\/www.setterirlandese.net\/en\/irish-setter-female\/#primaryimage"},"thumbnailUrl":"https:\/\/www.setterirlandese.net\/wp-content\/uploads\/2022\/03\/setter-irlandesi-femmina.jpg","datePublished":"2022-03-01T15:56:47+00:00","dateModified":"2025-12-05T16:41:41+00:00","description":"Female Irish Setters - Welcome to the page, below you can find out which females are part of our kennel.","inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.setterirlandese.net\/en\/irish-setter-female\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.setterirlandese.net\/en\/irish-setter-female\/#primaryimage","url":"https:\/\/www.setterirlandese.net\/wp-content\/uploads\/2022\/03\/setter-irlandesi-femmina.jpg","contentUrl":"https:\/\/www.setterirlandese.net\/wp-content\/uploads\/2022\/03\/setter-irlandesi-femmina.jpg","width":600,"height":314},{"@type":"WebSite","@id":"https:\/\/www.setterirlandese.net\/en\/#website","url":"https:\/\/www.setterirlandese.net\/en\/","name":"Setter Irlandese Scarna&#039;s Red Dream","description":"Allevamento Setter Irlandesi","publisher":{"@id":"https:\/\/www.setterirlandese.net\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.setterirlandese.net\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.setterirlandese.net\/en\/#organization","name":"Setter Irlandese Scarna&#039;s Red Dream","url":"https:\/\/www.setterirlandese.net\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.setterirlandese.net\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.setterirlandese.net\/wp-content\/uploads\/2022\/02\/logo-scarnas-red-dream.png","contentUrl":"https:\/\/www.setterirlandese.net\/wp-content\/uploads\/2022\/02\/logo-scarnas-red-dream.png","width":624,"height":624,"caption":"Setter Irlandese Scarna&#039;s Red Dream"},"image":{"@id":"https:\/\/www.setterirlandese.net\/en\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.setterirlandese.net\/en\/wp-json\/wp\/v2\/pages\/2603","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.setterirlandese.net\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.setterirlandese.net\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.setterirlandese.net\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.setterirlandese.net\/en\/wp-json\/wp\/v2\/comments?post=2603"}],"version-history":[{"count":57,"href":"https:\/\/www.setterirlandese.net\/en\/wp-json\/wp\/v2\/pages\/2603\/revisions"}],"predecessor-version":[{"id":5794,"href":"https:\/\/www.setterirlandese.net\/en\/wp-json\/wp\/v2\/pages\/2603\/revisions\/5794"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.setterirlandese.net\/en\/wp-json\/wp\/v2\/media\/2857"}],"wp:attachment":[{"href":"https:\/\/www.setterirlandese.net\/en\/wp-json\/wp\/v2\/media?parent=2603"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}